{"id":48522,"date":"2023-02-17T19:14:10","date_gmt":"2023-02-17T22:14:10","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369.jpg"},"modified":"2023-02-17T19:14:10","modified_gmt":"2023-02-17T22:14:10","slug":"img_1369-jpg","status":"inherit","type":"attachment","link":"https:\/\/maricatotal.com.br\/site\/img_1369-jpg\/","title":{"rendered":"img_1369.jpg"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-48522","attachment","type-attachment","status-inherit","hentry"],"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-300x169.jpg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-768x433.jpg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":577,"file":"2023\/02\/img_1369.jpg","filesize":117801,"sizes":{"medium":{"file":"img_1369-300x169.jpg","width":300,"height":169,"filesize":10444,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-300x169.jpg"},"thumbnail":{"file":"img_1369-150x150.jpg","width":150,"height":150,"filesize":5412,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-150x150.jpg"},"medium_large":{"file":"img_1369-768x433.jpg","width":768,"height":433,"filesize":43146,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-768x433.jpg"},"colormag-highlighted-post":{"file":"img_1369-392x272.jpg","width":392,"height":272,"filesize":17637,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-392x272.jpg"},"colormag-featured-post-medium":{"file":"img_1369-390x205.jpg","width":390,"height":205,"filesize":14851,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-390x205.jpg"},"colormag-featured-post-small":{"file":"img_1369-130x90.jpg","width":130,"height":90,"filesize":3528,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-130x90.jpg"},"colormag-featured-image":{"file":"img_1369-800x445.jpg","width":800,"height":445,"filesize":45358,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369-800x445.jpg"},"full":{"file":"img_1369.jpg","width":1024,"height":577,"mime_type":"image\/jpeg","source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/02\/img_1369.jpg","filename":"img_1369.jpg","filesize":117801,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/48522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=48522"}]}}