{"id":10011,"date":"2020-05-11T16:27:51","date_gmt":"2020-05-11T19:27:51","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=10011"},"modified":"2020-05-17T22:32:36","modified_gmt":"2020-05-18T01:32:36","slug":"mae-do-vereador-fabiano-novaes-nao-morreu-de-covid-19","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/05\/11\/mae-do-vereador-fabiano-novaes-nao-morreu-de-covid-19\/","title":{"rendered":"M\u00c3E DO VEREADOR FABIANO NOVAES N\u00c3O MORREU DE COVID-19"},"content":{"rendered":"\n<p>C\u00e9lia Regina Novaes Rocha, m\u00e3e do vereador Fabiano Novaes (DEM), n\u00e3o morreu de Covid-19, segundo o laudo de \u00f3bito divulgado pelo Laborat\u00f3rio Central Noel Nutels (Lacen) nesta segunda-feira (11).<\/p>\n\n\n\n<p>O vereador esclareceu a morte da m\u00e3e em nota, que foi de pneumonia e choque s\u00e9ptico.<\/p>\n\n\n\n<p><strong>NOTA DE ESCLARECIMENTO<\/strong><\/p>\n\n\n\n<p>Hoje, segunda-feira, 11 de maio de 2020, um dia ap\u00f3s o dia em que comemoramos o dia das m\u00e3es, reuni for\u00e7as e tomei coragem de vir atrav\u00e9s desta nota agradecer a imprensa e todos amigos que sentiram com a nossa dor e de alguma forma se manifestaram com um apoio neste momento dif\u00edcil que estamos passando. Por conta disso, me sinto na obriga\u00e7\u00e3o moral de compartilhar com voc\u00eas a not\u00edcia do laudo da morte de minha m\u00e3e, que recebemos somente hoje. Confesso que esse resultado n\u00e3o faz muita diferen\u00e7a, uma vez que n\u00e3o a tenho aqui juntamente comigo, mas como foi amplamente divulgado que o caso era suspeita de COVID-19, precisamos aqui explicar todo ocorrido. <\/p>\n\n\n\n<p>Por conta do COVID, todos n\u00f3s mudamos as nossas rotinas e para proteger meus pais, ainda que doesse o afastamento social, adotamos a pr\u00e1tica para preserva-los. Evitava de levar meus filhos para a casa deles, mas n\u00e3o deixei um s\u00f3 dia de estar presente, levando tudo que fosse necess\u00e1rio para que n\u00e3o precisassem ir a rua. Fiz isso, respeitando todas as medidas de seguran\u00e7a para protege-los. Em determinado momento, percebi que minha m\u00e3e come\u00e7ou a apresentar uma dificuldade respirat\u00f3ria, mas sem febre, sem tosse e sem nenhum outro sintoma que pudesse nos indicar uma preocupa\u00e7\u00e3o com a doen\u00e7a em quest\u00e3o. Observamos que a glicose estava alterada, mas a press\u00e3o estava boa e ach\u00e1vamos que era problema emocional, pois ela ja tinha passado por um quadro parecido anteriormente, por isso agendei uma consulta com psiquiatra, que n\u00e3o chegou acontecer. Almo\u00e7amos junto na quinta-feira, ela estava com pouco apetite, me pediu para comprar uma quentinha com fil\u00e9 de peixe, mas comprei o fil\u00e9 e caprichamos um almo\u00e7o sem saber que seria nosso \u00faltimo juntos, eu, ela, Elayne e meu pai. Na sexta feira, ela estava do mesmo jeito, comeu muito pouco porque eu forcei dizendo que se n\u00e3o se alimentasse eu teria que leva-la para o hospital, comeu e disse que depois que comia se sentia melhor. No s\u00e1bado ela parecia um pouco melhor, mas na hora do almo\u00e7o n\u00e3o se sentou conosco conevercei com a minha m\u00e3e que queria a levar para o hospital, mas ela dizia que n\u00e3o precisava, que iria se alimentar, eu iria levar ela no psiquiatra na ter\u00e7a, ela tomaria um rem\u00e9dio e ficaria boa. Depois que ela comeu um pouquinho vim para casa a tarde e voltei a noite com toda fam\u00edlia e n\u00e3o imagin\u00e1vamos que seria a despedida dos netos. Observamos que a glicose estava alta sendo necess\u00e1rio aplica\u00e7\u00e3o de insulina para regular. Neste s\u00e1bado, mesmo querendo ficar na casa dela, voltei para minha casa, pois achava que se ficasse l\u00e1 com as crian\u00e7as estaria incomodando ela que n\u00e3o estava bem, mas acredit\u00e1vamos que tudo isso era resultado de problema emocional, como j\u00e1 havia acontecido anteriormente e tudo ficaria bem. <\/p>\n\n\n\n<p>Na madrugada de s\u00e1bado, \u00e0s 4 horas da manh\u00e3, acordei assustado depois de SONHAR com minha m\u00e3e agonizando e dizendo que n\u00e3o iria resistir e que iria morrer. Bateu uma ang\u00fastia, um desespero e como havia combinado com ela liguei de madrugada e falou comigo que estava tudo bem. Pediu que eu chegasse cedo para medir a glicose, pois queria tomar caf\u00e9 para se sentir melhor. Assim eu fiz, cheguei cedo, testei a glicose e aferi a press\u00e3o. A press\u00e3o me deixou preocupado, pois estava 9:8, falei com minha irm\u00e3 e mesmo contrariando a vontade da minha m\u00e3e, fomos para o HUAP, no caminho, presenciei aquela agonia que vi no sonho segurei a m\u00e3o dela enquanto dirigia e apertava na mesma intensidade que estava o meu cora\u00e7\u00e3o e ouvi dos l\u00e1bios dela que se tivesse asas sairia voando, naquele momento meu cora\u00e7\u00e3o tremeu. Chegando l\u00e1 foi atendida na emerg\u00eancia e foi tratada como suspeita de COVID-19 porque reclamava de falta de ar. Descobriram que ela estava com pneumonia, o que nos deixou assustado, pois n\u00e3o apresentava tosse, secre\u00e7\u00e3o e nada do g\u00eanero. Encaminharam ela para o setor do COVID e isso nos deixou muito assustado, pois era o que ela e n\u00f3s tem\u00edamos. Poucas horas depois recebemos a not\u00edcia do \u00f3bito. <\/p>\n\n\n\n<p>Mexendo nas coisas da minha m\u00e3e esta semana descobrimos que tinha uma consulta marcada com o pneumologista, mas foi desmarcada por causa do COVID e vejam s\u00f3, o laudo da morte foi de pneumonia e choque s\u00e9ptico com suspeita de COVID. Suspeita esta que hoje N\u00c3O FOI CONFIRMADA ap\u00f3s receber o resultado do teste realizado no HUAP. A morte da minha m\u00e3e n\u00e3o teve como causa o COVID-19.  Mas esta doen\u00e7a maldita nos privou de um atendimento m\u00e9dico mais adequado, nos deixou inseguro para buscar aux\u00edlio no hospital anteriormente, nos afastou e deixamos de fazer o que sempre faz\u00edamos. Este mal nos impediu de abra\u00e7ar e at\u00e9 mesmo nos despedir da pessoa que tanto amava. Mas acredito que nada acontece sem que haja a permiss\u00e3o de Deus. <\/p>\n\n\n\n<p>O CAUSA DIRETA DA MORTE DA MINHA M\u00c3E N\u00c3O FOI COVID-19, MAS ESTA DOEN\u00c7A \u00c9 REAL E EST\u00c1 TOMANDO FORMA E ROSTOS CONHECIDOS. N\u00c3O DESAFIE! SIGA AS ORIENTA\u00c7\u00d5ES DOS M\u00c9DICOS E PROFISSIONAIS DA SA\u00daDE.  RESPEITE A VIDA! AME O PR\u00d3XIMO! TENHA F\u00c9! TUDO ISSO VAI PASSAR.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"1024\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/05\/cc5b264e-19cb-4aaa-9970-b616d004e2bf-498x1024.jpg\" alt=\"\" class=\"wp-image-10013\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/05\/cc5b264e-19cb-4aaa-9970-b616d004e2bf-498x1024.jpg 498w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/05\/cc5b264e-19cb-4aaa-9970-b616d004e2bf-146x300.jpg 146w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/05\/cc5b264e-19cb-4aaa-9970-b616d004e2bf.jpg 720w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e9lia Regina Novaes Rocha, m\u00e3e do vereador Fabiano Novaes (DEM), n\u00e3o morreu de Covid-19, segundo o laudo de \u00f3bito divulgado<\/p>\n","protected":false},"author":1,"featured_media":10014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-10011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=10011"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/10014"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=10011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=10011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=10011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}