{"id":10019,"date":"2020-05-11T19:25:45","date_gmt":"2020-05-11T22:25:45","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=10019"},"modified":"2020-05-17T22:32:36","modified_gmt":"2020-05-18T01:32:36","slug":"prefeitura-desenvolve-programa-de-amparo-ao-emprego","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/05\/11\/prefeitura-desenvolve-programa-de-amparo-ao-emprego\/","title":{"rendered":"PREFEITURA DESENVOLVE PROGRAMA DE AMPARO AO EMPREGO"},"content":{"rendered":"\n<p>Buscando a manuten\u00e7\u00e3o dos empregos formais na cidade, a Prefeitura de Maric\u00e1 enviar\u00e1 a C\u00e2mara Municipal, at\u00e9 o fim desta semana, mais um importante programa que visa amenizar os impactos na economia local causados pela pandemia de Covid-19.<\/p>\n\n\n\n<p>Idealizado pela Secretaria de Desenvolvimento Econ\u00f4mico, Com\u00e9rcio, Ind\u00fastria, Petr\u00f3leo e Portos, o Programa de Amparo ao Emprego (PAE), iniciativa in\u00e9dita no pa\u00eds, contar\u00e1 com um investimento de R$ 15 milh\u00f5es\/m\u00eas, alcan\u00e7ando por volta de 15 mil cadastros, no qual prev\u00ea o pagamento de um sal\u00e1rio m\u00ednimo (R$ 1.045), durante tr\u00eas meses, aos empregados formais de empresas registradas no munic\u00edpio, afetadas pela pandemia e com o efetivo de at\u00e9 49 funcion\u00e1rios.<\/p>\n\n\n\n<p>Segundo Igor Sardinha, secret\u00e1rio da pasta, o PAE chega para fortalecer as demais medidas j\u00e1 implantadas na cidade para o enfrentamento da atual crise.<\/p>\n\n\n\n<p>\u201cEssa a\u00e7\u00e3o visando a prote\u00e7\u00e3o dos empregos formais na cidade \u00e9 mais uma medida econ\u00f4mica que a prefeitura executa buscando ofertar a tranquilidade m\u00ednima necess\u00e1ria para que o cidad\u00e3o consiga praticar o seu isolamento social com relativa tranquilidade\u201d, afirma o secret\u00e1rio.<\/p>\n\n\n\n<p>De acordo com a Secretaria de Desenvolvimento Econ\u00f4mico, a participa\u00e7\u00e3o no programa pelos empreendedores do munic\u00edpio ser\u00e1 realizada nos mesmos moldes do PAT (Programa de Amparo ao Trabalhador), j\u00e1 lan\u00e7ado. O empres\u00e1rio interessado dever\u00e1 entrar em um sistema desenvolvido pela prefeitura, no qual ir\u00e1 preencher os dados da sua empresa e dos seus funcion\u00e1rios, comprovando mensalmente esse v\u00ednculo.<\/p>\n\n\n\n<p>Com os micro e pequenos empres\u00e1rios, os microempreendedores individuais (MEIs) tamb\u00e9m poder\u00e3o solicitar o auxilio. Uma das exig\u00eancias a todos os beneficiados ser\u00e1 a manuten\u00e7\u00e3o dos respectivos empregados por igual per\u00edodo do programa.<\/p>\n\n\n\n<p>Vale lembrar que entre as principais medidas da prefeitura no combate \u00e0 pandemia, em execu\u00e7\u00e3o no munic\u00edpio, est\u00e3o al\u00e9m do PAT (pagamento de um sal\u00e1rio m\u00ednimo, convertido em Mumbucas, por tr\u00eas meses podendo ser estendido por mais tr\u00eas meses); antecipa\u00e7\u00e3o do abono natalino de 130 Mumbucas para os mais de 40 mil benefici\u00e1rios do programa Renda B\u00e1sica da Cidadania (RBC); amplia\u00e7\u00e3o do cr\u00e9dito mensal do RBC para 300 Mumbucas por tr\u00eas meses, entrega de cestas b\u00e1sicas aos alunos da rede p\u00fablica e o rec\u00e9m-lan\u00e7ado Fomenta Maric\u00e1 que consiste em uma linha de cr\u00e9dito emergencial para as micro e pequenas empresas de Maric\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buscando a manuten\u00e7\u00e3o dos empregos formais na cidade, a Prefeitura de Maric\u00e1 enviar\u00e1 a C\u00e2mara Municipal, at\u00e9 o fim desta<\/p>\n","protected":false},"author":1,"featured_media":10020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-10019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=10019"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/10020"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=10019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=10019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=10019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}