{"id":10066,"date":"2020-05-13T10:32:48","date_gmt":"2020-05-13T13:32:48","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=10066"},"modified":"2020-05-17T22:33:36","modified_gmt":"2020-05-18T01:33:36","slug":"prefeitura-promove-semana-de-palestras-online-sobre-enfermagem","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/05\/13\/prefeitura-promove-semana-de-palestras-online-sobre-enfermagem\/","title":{"rendered":"PREFEITURA PROMOVE SEMANA DE PALESTRAS ONLINE SOBRE ENFERMAGEM"},"content":{"rendered":"\n<p>Dia 12 de maio \u00e9 o Dia Internacional da Enfermagem e a Secretaria de Sa\u00fade de Maric\u00e1 est\u00e1 organizando diversas atividades para marcar a data, levando em conta a necessidade do isolamento social por conta da pandemia da Covid-19.<\/p>\n\n\n\n<p>No Hospital Municipal Dr. Ernesto Che Guevara, ser\u00e1 comemorado a \u201c1\u00aa Semana da Enfermagem e Controle de Infec\u00e7\u00e3o Hospitalar\u201d, de 12 a 15 de maio com palestras online, via aplicativo. A palestra de abertura desta ter\u00e7a-feira (12) teve como tema: &nbsp;\u201cO sentido da vida para o ser que cuida\u201d, &nbsp;com Vivian Linhares, enfermeira obst\u00e9trica, mestre em Ci\u00eancias do Cuidado em Sa\u00fade pela EEAAC \/ UFF.<\/p>\n\n\n\n<p>\u201cFazer online foi bem visto tamb\u00e9m para profissionais de diferentes \u00e1reas porque eles poderiam ter acesso ao conte\u00fado que, se fosse presencial, seria apenas para enfermeiros\u201d, comenta a enfermeira C\u00edntia Lima, uma das organizadoras.<\/p>\n\n\n\n<p>A enfermeira Marcelle de Oliveira Resende, de 34 anos, que atua no Hospital Municipal Conde Modesto Leal, possui 13 anos de forma\u00e7\u00e3o e foi motivada a cursar Enfermagem pelo diagn\u00f3stico surpreendente de sua m\u00e3e.<\/p>\n\n\n\n<p>\u201cH\u00e1 18 anos, minha m\u00e3e foi diagnosticada com Esclerose M\u00faltipla e era necess\u00e1ria &nbsp;uma medica\u00e7\u00e3o espec\u00edfica diariamente. Isso me fez perceber que minha m\u00e3e precisaria de um cuidado especial a partir daquele momento, por ser uma doen\u00e7a que n\u00e3o tem cura. Foi quando decidi fazer enfermagem. At\u00e9 hoje ela toma medica\u00e7\u00e3o. Tomei essa decis\u00e3o porque eu amo cuidar e porque senti que deveria me aperfei\u00e7oar para estar de prontid\u00e3o para quando minha m\u00e3e precisasse\u201d, conta Marcele.<\/p>\n\n\n\n<p>Segundo a m\u00e9dica e diretora executiva do Hospital Che Guevara, Michele Silvares, n\u00e3o existe pensar na \u00e1rea de Sa\u00fade sem o enfermeiro, j\u00e1 que ele \u00e9 o finalizador, a pessoa que cuida do procedimento e que, atualmente, est\u00e1 alcan\u00e7ando a valoriza\u00e7\u00e3o de sua fun\u00e7\u00e3o, que atua aprimorando a qualidade em sa\u00fade.<\/p>\n\n\n\n<p>\u201cO profissional da enfermagem \u00e9 a ferramenta de gest\u00e3o que faz com que os processos caminhem de forma segura e com qualidade em toda unidade de sa\u00fade. Ele tem o manejo maior das situa\u00e7\u00f5es, \u00e9 um facilitador da vida do m\u00e9dico\u201d, afirma Michele.<\/p>\n\n\n\n<p>O Hospital Municipal Conde Modesto Leal, no Centro; o Posto de Sa\u00fade Santa Rita, em Itaipua\u00e7u; a Unidade de Pronto Atendimento (UPA), de Ino\u00e3; e o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) receber\u00e3o a \u201cSemana da Enfermagem\u201d, com homenagens, brindes e um caf\u00e9 da tarde especial, nesta quarta-feira (13\/05), al\u00e9m de outras atividades durante a semana.<\/p>\n\n\n\n<p>Na rede prim\u00e1ria de sa\u00fade \u2013 porta de entrada para o SUS \u2013, Maric\u00e1 conta com 24 unidades, com 42 equipes de sa\u00fade da fam\u00edlia, distribu\u00eddas nos quatro distritos de Maric\u00e1. A comemora\u00e7\u00e3o da data ser\u00e1 feita virtualmente tamb\u00e9m, parabenizando os profissionais que atuam nas unidades.<\/p>\n\n\n\n<p>Embora o Dia Internacional da Enfermagem seja celebrado mundialmente desde 1965, oficialmente esta data s\u00f3 foi estabelecida em 1974, a partir da decis\u00e3o do Conselho Internacional de Enfermeiros. O dia 12 de maio foi escolhido como homenagem ao nascimento, em Floren\u00e7a, It\u00e1lia, de Florence Nightingale, considerada a \u201cm\u00e3e\u201d da enfermagem moderna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia 12 de maio \u00e9 o Dia Internacional da Enfermagem e a Secretaria de Sa\u00fade de Maric\u00e1 est\u00e1 organizando diversas<\/p>\n","protected":false},"author":1,"featured_media":10067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-10066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=10066"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/10067"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=10066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=10066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=10066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}