{"id":10514,"date":"2020-05-27T08:04:44","date_gmt":"2020-05-27T11:04:44","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=10514"},"modified":"2020-05-27T08:04:46","modified_gmt":"2020-05-27T11:04:46","slug":"inscricoes-para-o-pae-ja-estao-disponiveis","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/05\/27\/inscricoes-para-o-pae-ja-estao-disponiveis\/","title":{"rendered":"INSCRI\u00c7\u00d5ES PARA O PAE J\u00c1 EST\u00c3O DISPON\u00cdVEIS"},"content":{"rendered":"\n<p>Come\u00e7aram \u00e0s 18h desta ter\u00e7a-feira (26\/05) e v\u00e3o at\u00e9 o dia 05\/06 as inscri\u00e7\u00f5es para o Programa de Amparo ao Emprego (PAE) \u2013 mais uma medida da Prefeitura de Maric\u00e1 de combate a pandemia da Covid-19. Para se inscreverem, os interessados ter\u00e3o que acessar o Portal SIM (<a href=\"https:\/\/sim.marica.rj.gov.br\/PAE\/1\">clique aqui<\/a>). L\u00e1, os empregadores dever\u00e3o comprovar mensalmente a rela\u00e7\u00e3o da folha salarial, com a perman\u00eancia do v\u00ednculo de todos os empregados, sem que haja redu\u00e7\u00e3o salarial dos funcion\u00e1rios, j\u00e1 que o benef\u00edcio ser\u00e1 revertido exclusivamente para o pagamento da folha salarial.<\/p>\n\n\n\n<p>O benef\u00edcio ser\u00e1 concedido apenas \u00e0quelas empresas com efetivo de at\u00e9 49 empregados e que tiveram suas atividades interrompidas por conta do isolamento social, a fim de conter a dissemina\u00e7\u00e3o do novo coronav\u00edrus.&nbsp;A iniciativa prev\u00ea o pagamento de um sal\u00e1rio m\u00ednimo (R$ 1.045) por um per\u00edodo de tr\u00eas meses ao empregado vinculado a microempreendedor individual (MEIs) e trabalhadores de micro ou pequenas empresas instaladas na cidade. A estimativa \u00e9 que as 1.448 micro e pequenas empresas e os 7.195 MEIs ativos com inscri\u00e7\u00e3o no munic\u00edpio sejam beneficiados.<\/p>\n\n\n\n<p>O secret\u00e1rio de Desenvolvimento Econ\u00f4mico, Com\u00e9rcio, Ind\u00fastria, Petr\u00f3leo e Portos, Igor Sardinha, j\u00e1 designou os integrantes da Comiss\u00e3o de Avalia\u00e7\u00e3o e Dilig\u00eancia dos Requerimentos ao PAE. \u201cSempre buscamos durante a pandemia fazer com que as medidas na \u00e1rea da sa\u00fade caminhem em paralelo com as medidas econ\u00f4micas e de prote\u00e7\u00e3o social. O PAE age exatamente nesse sentido ao auxiliar o empres\u00e1rio local e proteger o emprego dos trabalhadores\u201d, afirmou.<\/p>\n\n\n\n<p>Para se candidatar \u00e9 necess\u00e1rio que o interessado esteja enquadrado em alguns crit\u00e9rios: a empresa precisa &nbsp;ter sede no munic\u00edpio; o aut\u00f4nomo deve comprovar que \u00e9 registrado como MEI; que \u00e9 microempresa ou empresa de pequeno porte, ter comprova\u00e7\u00e3o ou solicita\u00e7\u00e3o de inscri\u00e7\u00e3o municipal; ter contrato social e cart\u00e3o de CNPJ; declara\u00e7\u00e3o que tiveram suas atividades suspensas, mesmo que parcialmente, por consequ\u00eancia do isolamento, entre outros.<\/p>\n\n\n\n<p>O PAE integra o pacote econ\u00f4mico de enfrentamento \u00e0 Covid-19, que j\u00e1 conta com o Fomenta Maric\u00e1 e o Programa de Amparo ao Trabalhador (PAT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7aram \u00e0s 18h desta ter\u00e7a-feira (26\/05) e v\u00e3o at\u00e9 o dia 05\/06 as inscri\u00e7\u00f5es para o Programa de Amparo ao<\/p>\n","protected":false},"author":1,"featured_media":10515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-10514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=10514"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/10514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/10515"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=10514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=10514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=10514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}