{"id":11018,"date":"2020-06-09T07:57:02","date_gmt":"2020-06-09T10:57:02","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=11018"},"modified":"2020-06-09T07:57:03","modified_gmt":"2020-06-09T10:57:03","slug":"rio-justica-derruba-flexibilizacao-do-isolamento-social-no-estado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/06\/09\/rio-justica-derruba-flexibilizacao-do-isolamento-social-no-estado\/","title":{"rendered":"RIO: JUSTI\u00c7A DERRUBA FLEXIBILIZA\u00c7\u00c3O DO ISOLAMENTO SOCIAL NO ESTADO"},"content":{"rendered":"\n<p>A Justi\u00e7a derrubou os decretos que relaxavam o isolamento social no estado e no munic\u00edpio do Rio. A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico e pela Defensoria P\u00fablica estadual. <\/p>\n\n\n\n<p>Na decis\u00e3o, o juiz Bruno Bodart, da 7\u00aa Vara de Fazenda P\u00fablica da capital afirma que as decis\u00f5es municipal e estadual n\u00e3o revelam elementos t\u00e9cnicos suficientes para dar embasamento \u00e0 reabertura da economia.<\/p>\n\n\n\n<p>Segundo o documento, que se baseia em estudos da Funda\u00e7\u00e3o Oswaldo Cruz, o relaxamento inadequado das medidas de isolamento social pode causar uma acelera\u00e7\u00e3o do cont\u00e1gio pela Covid-19, de dif\u00edcil revers\u00e3o, mesmo que as restri\u00e7\u00f5es voltem a ser estabelecidas posteriormente.<\/p>\n\n\n\n<p>A Justi\u00e7a determinou, ainda, que o estado fiscalize o isolamento, de forma efetiva e&nbsp; coordenada com os munic\u00edpios.<\/p>\n\n\n\n<p>Em caso de descumprimento da ordem, a multa \u00e9 de R$ 50 mil \u00e0s pessoas f\u00edsicas do prefeito Marcelo Crivella e do governador Wilson Witzel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a derrubou os decretos que relaxavam o isolamento social no estado e no munic\u00edpio do Rio. A a\u00e7\u00e3o foi<\/p>\n","protected":false},"author":1,"featured_media":11019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14,17],"tags":[],"class_list":["post-11018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/11018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=11018"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/11018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/11019"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=11018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=11018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=11018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}