{"id":11056,"date":"2020-06-10T10:58:18","date_gmt":"2020-06-10T13:58:18","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=11056"},"modified":"2020-06-10T10:58:19","modified_gmt":"2020-06-10T13:58:19","slug":"vacina-feita-na-fiocruz-contra-covid-19-esta-em-fase-de-estudos-pre-clinicos","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/06\/10\/vacina-feita-na-fiocruz-contra-covid-19-esta-em-fase-de-estudos-pre-clinicos\/","title":{"rendered":"VACINA FEITA NA FIOCRUZ CONTRA COVID-19 EST\u00c1 EM FASE DE ESTUDOS PR\u00c9-CL\u00cdNICOS"},"content":{"rendered":"\n<p>A vacina criada pela Funda\u00e7\u00e3o Oswaldo Cruz, por meio do Instituto de Tecnologia em Imunobiol\u00f3gicos (Bio-Manguinhos\/Fiocruz), para combater o coronav\u00edrus, est\u00e1 avan\u00e7ando em sua fase de testes e agora passar\u00e1 para uma nova fase de desenvolvimento chamada de &#8220;estudos pr\u00e9-cl\u00ednicos&#8221;, na qual a vacina ser\u00e1 testada em animais. Mesmo com o progresso da situa\u00e7\u00e3o, a vacina da Fio Cruz ainda passar\u00e1 por diversas fases e etapas e s\u00f3 deve estar pronta, pelo menos, em 2022.<\/p>\n\n\n\n<p>A Fiocruz, atrav\u00e9s da Bio-Manguinhos, foi eleita, pelo Minist\u00e9rio da Sa\u00fade, uma das respons\u00e1veis para garantir que o Brasil tenha autossufici\u00eancia na produ\u00e7\u00e3o de insumos na \u00e1rea da sa\u00fade e, por isso, a institui\u00e7\u00e3o busca, atrav\u00e9s de pesquisas, novas formas de combater a pandemia atual.&nbsp;<\/p>\n\n\n\n<p>A vacina utiliza como base partes de prote\u00ednas do v\u00edrus (os pept\u00eddeos antig\u00eanicos de c\u00e9lulas B e T) que, ao serem acoplados em nanopart\u00edculas, far\u00e3o a entrega desse material ao sistema imune das pessoas. Dessa forma, as pessoas que tomarem a vacina produzir\u00e3o anticorpos para defender o organismo do SARS-CoV-2, o agente que causa o coronav\u00edrus. As biomol\u00e9culas em quest\u00e3o foram produzidas por s\u00edntese qu\u00edmica, validadas in vitro e identificadas com a ajuda de um modelo computacional (in silico).<\/p>\n\n\n\n<p>No entanto, mesmo com todo esse processo e com o andamento da pesquisa sobre o caso, a vacina ainda deve passar por muitas fases at\u00e9 que fique pronta. Na pr\u00f3xima etapa do projeto, a Fiocruz deve realizar avalia\u00e7\u00f5es &#8220;in vivo&#8221; para entender a imunidade causada pela vacina e Funda\u00e7\u00e3o deve realizar novas formula\u00e7\u00f5es vacinais das biomol\u00e9culas acopladas em nanopart\u00edculas. Depois disso, o estudo pr\u00e9-cl\u00ednico chega ao fim e passar\u00e1 para os estudos cl\u00ednicos, que v\u00e3o determinar novas fases como a I, II e III.<\/p>\n\n\n\n<p>Vale lembrar que a vacina sint\u00e9tica, como \u00e9 o caso da produzida contra o coronav\u00edrus pela Fiocruz, tem custos menores e \u00e9 um estudo de r\u00e1pido desenvolvimento, al\u00e9m de ser de f\u00e1cil armazenamento. Esse tipo de vacina tamb\u00e9m \u00e9 produzida sem a necessidade de instala\u00e7\u00f5es de biosseguran\u00e7a n\u00edvel 3, pelo menos, n\u00e3o nas primeiras etapas do processo.<\/p>\n\n\n\n<p>A Fiocruz desenvolve vacinas e projetos para garantir futura distribui\u00e7\u00e3o do material produzido e aprovado no Sistema \u00danico de Sa\u00fade (SUS). Por isso, a Fiocruz tamb\u00e9m est\u00e1 estudando uma outra vacina que busca trabalhar com fragmentos de ant\u00edgenos para estimular uma resposta mais r\u00e1pida do sistema imunol\u00f3gico dos pacientes. No entanto, a vacina em quest\u00e3o ainda est\u00e1 em fase de testes e busca entender diferentes constru\u00e7\u00f5es da prote\u00edna S, a prote\u00edna ligada ao v\u00edrus SARS-CoV-2, com as c\u00e9lulas do paciente. Al\u00e9m desses projetos, a Fiocruz debate outras solu\u00e7\u00f5es para a pandemia atual e parcerias com outras empresas e apoiadores internacionais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vacina criada pela Funda\u00e7\u00e3o Oswaldo Cruz, por meio do Instituto de Tecnologia em Imunobiol\u00f3gicos (Bio-Manguinhos\/Fiocruz), para combater o coronav\u00edrus,<\/p>\n","protected":false},"author":1,"featured_media":11057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-11056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/11056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=11056"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/11056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/11057"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=11056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=11056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=11056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}