{"id":12025,"date":"2020-07-06T21:13:08","date_gmt":"2020-07-07T00:13:08","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=12025"},"modified":"2020-07-06T21:33:49","modified_gmt":"2020-07-07T00:33:49","slug":"internautas-registram-aglomeracoes-no-parque-nanci","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/07\/06\/internautas-registram-aglomeracoes-no-parque-nanci\/","title":{"rendered":"INTERNAUTAS REGISTRAM AGLOMERA\u00c7\u00d5ES NO PARQUE NANCI"},"content":{"rendered":"\n<p>O Parque Nanci, maior parque a c\u00e9u aberto de Maric\u00e1, foi visto com grande movimenta\u00e7\u00e3o de pessoas e com aglomera\u00e7\u00f5es na noite desta segunda-feira (06).<\/p>\n\n\n\n<p>Inagurado na \u00faltima sexta-feira, o local recebeu uma enorme quantidade de pessoas neste fim de semana, mesmo com a pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p>Nesta noite, jovens foram ao local para praticar esportes como altinha e futsal.<\/p>\n\n\n\n<p>A cidade conta com 1510 casos confirmados, 1302 curados e 57 \u00f3bitos.<\/p>\n\n\n\n<p>A Secretaria de Sa\u00fade Municipal refor\u00e7a a import\u00e2ncia do distanciamento social, para combater a Covid-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Parque Nanci, maior parque a c\u00e9u aberto de Maric\u00e1, foi visto com grande movimenta\u00e7\u00e3o de pessoas e com aglomera\u00e7\u00f5es<\/p>\n","protected":false},"author":1,"featured_media":12026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-12025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/12025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=12025"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/12025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/12026"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=12025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=12025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=12025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}