{"id":12393,"date":"2020-07-15T23:25:54","date_gmt":"2020-07-16T02:25:54","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=12393"},"modified":"2020-07-15T23:25:56","modified_gmt":"2020-07-16T02:25:56","slug":"defesa-civil-tem-base-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/07\/15\/defesa-civil-tem-base-em-itaipuacu\/","title":{"rendered":"DEFESA CIVIL TEM BASE EM ITAIPUA\u00c7U"},"content":{"rendered":"\n<p>A Secretaria de Prote\u00e7\u00e3o e Defesa Civil tem agora uma base em Itaipua\u00e7u, que funciona no Centro Administrativo, e atender\u00e1 tamb\u00e9m as ocorr\u00eancias em Ino\u00e3. A unidade conta com seis agentes por dia, que est\u00e3o preparados para realizar desde vistorias preventivas, mapeamentos das \u00e1reas de risco e atendimento em casos de emerg\u00eancia.<\/p>\n\n\n\n<p>A escolha do local para a base levou em conta que as regi\u00f5es t\u00eam problemas de inunda\u00e7\u00e3o, alagamento nas constru\u00e7\u00f5es (estruturais) e de ordem geol\u00f3gica. Segundo coordenador t\u00e9cnico do \u00f3rg\u00e3o, major Wellington Silva, Maric\u00e1 \u00e9 a primeira Defesa Civil do Estado que tem duas bases distribu\u00eddas dentro de um munic\u00edpio.<\/p>\n\n\n\n<p>\u201c\u00c9 de suma import\u00e2ncia essa nova base, pois faz com a gente tenha uma maior efic\u00e1cia mediante as demandas da popula\u00e7\u00e3o, em uma regi\u00e3o densamente povoada como Itaipua\u00e7u e Ino\u00e3. Nos \u00faltimos dois anos constatamos que 60% das ocorr\u00eancias do munic\u00edpio s\u00e3o desses locais. Estar mais pr\u00f3ximo faz com que a gente possa dar a agilidade que a popula\u00e7\u00e3o precisa e tamb\u00e9m se sentem mais seguros\u201d, explica o coordenador t\u00e9cnico.<\/p>\n\n\n\n<p>Os moradores da regi\u00e3o que precisarem do atendimento da Defesa Civil devem ir ao Centro Administrativo, de segunda a sexta-feira, das 8h \u00e0s 17h. O servi\u00e7o tamb\u00e9m funciona pelo telefone (21) 97019-5395 que tamb\u00e9m \u00e9 WhatsApp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Prote\u00e7\u00e3o e Defesa Civil tem agora uma base em Itaipua\u00e7u, que funciona no Centro Administrativo, e atender\u00e1<\/p>\n","protected":false},"author":1,"featured_media":12394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-12393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/12393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=12393"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/12393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/12394"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=12393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=12393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=12393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}