{"id":13584,"date":"2020-08-19T11:26:49","date_gmt":"2020-08-19T14:26:49","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=13584"},"modified":"2020-08-19T11:26:51","modified_gmt":"2020-08-19T14:26:51","slug":"passaros-silvestres-sao-resgatados-pelo-inea-e-guarda-municipal-em-itapeba","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/08\/19\/passaros-silvestres-sao-resgatados-pelo-inea-e-guarda-municipal-em-itapeba\/","title":{"rendered":"P\u00c1SSAROS SILVESTRES S\u00c3O RESGATADOS PELO INEA E GUARDA MUNICIPAL EM ITAPEBA"},"content":{"rendered":"\n<p>O Instituto Estadual do Ambiente (INEA) junto a Guarda Municipal de Maric\u00e1 apreenderam 15 p\u00e1ssaros que estavam em cativeiro no bairro de Itapeba, na manh\u00e3 desta quarta-feira (19).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, ap\u00f3s den\u00fancias, representantes do INEA e agentes da Guarda Municipal seguiram at\u00e9 uma resid\u00eancia no bairro, onde fizeram a apreens\u00e3o dos animais. <\/p>\n\n\n\n<p>Na a\u00e7\u00e3o, 11 trinca feros, 1 tico-tico-rei, 1 brejal e 2 coleiros foram resgatados. Os animais ser\u00e3o encaminhados para o Centro de Reabilita\u00e7\u00e3o e em seguida devolvidos para a natureza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Estadual do Ambiente (INEA) junto a Guarda Municipal de Maric\u00e1 apreenderam 15 p\u00e1ssaros que estavam em cativeiro no<\/p>\n","protected":false},"author":1,"featured_media":13585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/13584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=13584"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/13584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/13585"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=13584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=13584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=13584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}