{"id":13814,"date":"2020-08-31T07:59:52","date_gmt":"2020-08-31T10:59:52","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=13814"},"modified":"2020-08-31T07:59:53","modified_gmt":"2020-08-31T10:59:53","slug":"izaias-de-oliveira-segue-desaparecido-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/08\/31\/izaias-de-oliveira-segue-desaparecido-em-marica\/","title":{"rendered":"Izaias de Oliveira segue desaparecido em Maric\u00e1"},"content":{"rendered":"\n<p>Izaias de Oliveira Dias J\u00fanior, de 30 anos, est\u00e1 desaparecido desde a \u00faltima sexta-feira (28) no munic\u00edpio de Maric\u00e1. O homem \u00e9 motorista da lotada Maric\u00e1 &#8211; Rio do Ouro e funcion\u00e1rio da Prefeitura.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es de parentes, o \u00faltimo contato com Izaias foi \u00e0s 7h30 da manh\u00e3 com sua esposa. Logo depois, o homem desapareceu.<\/p>\n\n\n\n<p>Quem souber o paradeiro de Izaias de Oliveira entre contato no n\u00famero 2199743-0197 ou 2199106-3710.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Izaias de Oliveira Dias J\u00fanior, de 30 anos, est\u00e1 desaparecido desde a \u00faltima sexta-feira (28) no munic\u00edpio de Maric\u00e1. O<\/p>\n","protected":false},"author":1,"featured_media":13815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-13814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/13814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=13814"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/13814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/13815"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=13814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=13814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=13814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}