{"id":14487,"date":"2020-09-18T07:09:21","date_gmt":"2020-09-18T10:09:21","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=14487"},"modified":"2020-09-18T07:09:23","modified_gmt":"2020-09-18T10:09:23","slug":"covid-19-em-uma-semana-casos-caem-30-e-mortes-13","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/09\/18\/covid-19-em-uma-semana-casos-caem-30-e-mortes-13\/","title":{"rendered":"Covid-19: em uma semana, casos caem 30% e mortes, 13%"},"content":{"rendered":"\n<p>Os casos de covid-19 ca\u00edram 30% na semana epidemiol\u00f3gica 37 em rela\u00e7\u00e3o \u00e0 semana anterior. J\u00e1 as mortes registraram diminui\u00e7\u00e3o de 13% no mesmo intervalo. Foi a primeira vez em que as duas curvas apresentaram uma redu\u00e7\u00e3o acima de 10% juntas desde o in\u00edcio da pandemia.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1388255&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1388255&amp;o=node\"><\/p>\n\n\n\n<p>A evolu\u00e7\u00e3o das curvas de diagn\u00f3sticos e \u00f3bitos relacionados \u00e0 pandemia do novo coronav\u00edrus est\u00e1 no novo boletim epidemiol\u00f3gico sobre a doen\u00e7a do Minist\u00e9rio da Sa\u00fade, apresentado em entrevista coletiva&nbsp;hoje&nbsp;(17).<\/p>\n\n\n\n<p>A semana epidemiol\u00f3gica (SE) 37 compreende o intervalo de 6 a&nbsp;12 de setembro. A SE \u00e9 uma medida empregada por autoridades de sa\u00fade para analisar o desenvolvimento de uma determinada epidemia.<\/p>\n\n\n\n<p>Na SE 37 foram contabilizados 192.687 novos registros de casos de covid-19. Na semana anterior (SE 36), o n\u00famero havia sido de 276.847. A m\u00e9dia di\u00e1ria nesta \u00faltima semana epidemiol\u00f3gica foi de 27.527. A trajet\u00f3ria cresceu e come\u00e7ou uma tend\u00eancia de queda na SE 29, com uma leve recupera\u00e7\u00e3o entre as SE 34 e 36 e agora uma baixa expressiva.<\/p>\n\n\n\n<p>\u201cO Brasil vinha com plat\u00f4 e desde a 29\u00aa semana epidemiol\u00f3gica come\u00e7ou a\u00a0ter\u00a0uma tend\u00eancia de queda. Tivemos um pico no Sul na 35\u00aa semana, mas foi por registro dos novos casos. Quando houve atualiza\u00e7\u00e3o dos casos, j\u00e1 se confirmou uma tend\u00eancia de redu\u00e7\u00e3o. Da 36\u00aa para a 37 tivemos redu\u00e7\u00e3o bastante significativa de 30%\u201d, destacou o secret\u00e1rio de Vigil\u00e2ncia em Sa\u00fade, Arnaldo de Medeiros.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/GhAfXNjm0P-DvZt_rXGfjxiYZT8=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/slide_15_0.jpg?itok=pIVOhPZS\" alt=\"Evolu\u00e7\u00e3o do n\u00famero de novos registros de casos de covid-19 por semana epidemiol\u00f3gica\" title=\"Minist\u00e9rio da Sa\u00fade\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Evolu\u00e7\u00e3o do n\u00famero de novos registros de casos de covid-19 por semana epidemiol\u00f3gica &#8211;&nbsp;<strong>Minist\u00e9rio da Sa\u00fade<\/strong><\/h6>\n\n\n\n<p>J\u00e1 as mortes nesta semana totalizaram 5.007. Na SE 36, o n\u00famero havia sido de 5.741. A m\u00e9dia di\u00e1ria ficou em 715. \u201cQuando analisamos os \u00f3bitos, est\u00e1vamos com um plat\u00f4 por volta da 23\u00aa, por volta da 29\u00aa j\u00e1 vinha mostrando uma queda gradativa e a 36\u00aa e a 37\u00aa uma redu\u00e7\u00e3o de 13%. Quando no plat\u00f4 t\u00ednhamos por volta de 7 mil, tivemos agora 5 mil nesta \u00faltima semana\u201d, pontuou Arnaldo de Medeiros.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/xaSBQvYmXyBSAcbpOVIiPSfQ25g=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/slide_16.jpg?itok=zpHWKQ40\" alt=\"Evolu\u00e7\u00e3o do n\u00famero de novos registros de \u00f3bitos por semana epidemiol\u00f3gica\" title=\"Minist\u00e9rio da Sa\u00fade\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Evolu\u00e7\u00e3o do n\u00famero de novos registros de \u00f3bitos por semana epidemiol\u00f3gica &#8211;&nbsp;<strong>Minist\u00e9rio da Sa\u00fade<\/strong><\/h6>\n\n\n\n<h2 class=\"wp-block-heading\">Covid-19 nos estados<\/h2>\n\n\n\n<p>No mapa de casos, pela primeira vez o boletim epidemiol\u00f3gico n\u00e3o trouxe nenhum estado com aumento nos casos. Do total, 24 Unidades da Federa\u00e7\u00e3o tiveram redu\u00e7\u00e3o, sendo as mais expressivas em Santa Catarina (-79%) e Pernambuco (-43%). Permaneceram est\u00e1veis Piau\u00ed, Mato Grosso do Sul e Minas Gerais.<\/p>\n\n\n\n<p>No mapa de mortes, cinco estados apresentaram acr\u00e9scimos nas taxas, sendo as maiores em Pernambuco (48%) e Minas Gerais (12%). Um estado ficou estabilizado (Rio Grande do Sul) e 21 Unidades da Federa\u00e7\u00e3o tiveram queda em seus \u00edndices, sendo as mais intensas as do Amazonas (-77%) e Par\u00e1 (-49%).<\/p>\n\n\n\n<p>A maioria dos casos continuou no interior (62%), enquanto a menor parcela ocorreu nas regi\u00f5es metropolitanas (38%). J\u00e1 na compara\u00e7\u00e3o entre os \u00f3bitos, 53% ocorrem nas localidades do interior e 47%, nos grandes centros urbanos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/SrYXJNcuNW1HO8c5hoizpy8JsdY=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/slide_18_0.jpg?itok=TJ7SuPFX\" alt=\"Varia\u00e7\u00e3o de casos e \u00f3bitos entre as semanas epidemiol\u00f3gicas 36 e 37\" title=\"Minist\u00e9rio da Sa\u00fade\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Varia\u00e7\u00e3o de casos e \u00f3bitos entre as semanas epidemiol\u00f3gicas 36 e 37 &#8211;&nbsp;<strong>Minist\u00e9rio da Sa\u00fade<\/strong><\/h6>\n\n\n\n<h2 class=\"wp-block-heading\">Testes<\/h2>\n\n\n\n<p>At\u00e9 o momento, foram distribu\u00eddos aos estados 6,6 milh\u00f5es de rea\u00e7\u00f5es de testes laboratoriais (RT-PCR). Os laborat\u00f3rios p\u00fablicos processaram 3,4 milh\u00f5es de exames.\u00a0A rede privada realizou 2,5 milh\u00f5es de testes, totalizando 5,9 milh\u00f5es. J\u00e1 os testes r\u00e1pidos (sorol\u00f3gicos) totalizaram at\u00e9 agora 8 milh\u00f5es. (Ag\u00eancia Brasil)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os casos de covid-19 ca\u00edram 30% na semana epidemiol\u00f3gica 37 em rela\u00e7\u00e3o \u00e0 semana anterior. J\u00e1 as mortes registraram diminui\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":14488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-14487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/14487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=14487"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/14487\/revisions"}],"predecessor-version":[{"id":14489,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/14487\/revisions\/14489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/14488"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=14487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=14487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=14487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}