{"id":15406,"date":"2020-10-08T14:38:09","date_gmt":"2020-10-08T17:38:09","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=15406"},"modified":"2020-10-08T14:38:09","modified_gmt":"2020-10-08T17:38:09","slug":"rj-106-transito-em-meia-pista-para-obras-em-sao-jose-do-imbassai","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/10\/08\/rj-106-transito-em-meia-pista-para-obras-em-sao-jose-do-imbassai\/","title":{"rendered":"Rj-106: Tr\u00e2nsito em meia pista para obras em S\u00e3o Jos\u00e9 do Imbassa\u00ed"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1 segue realizando obras na Rodovia Amaral Peixoto, RJ-106, em S\u00e3o Jos\u00e9 do Imbassa\u00ed, interditando meia pista, nesta quinta-feira (08). A a\u00e7\u00e3o tem a finalidade de combater a enchentes no bairro.<\/p>\n\n\n\n<p>Tubula\u00e7\u00f5es seguem recebendo reparos e sendo substitu\u00eddas por homens e m\u00e1quinas a autarquia do Servi\u00e7o de Obras de Maric\u00e1 (SOMAR), para que as \u00e1guas das chuvas possam escoar diretamente para as galerias de drenagem.<\/p>\n\n\n\n<p>O tr\u00e2nsito no trecho \u00e9 lento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1 segue realizando obras na Rodovia Amaral Peixoto, RJ-106, em S\u00e3o Jos\u00e9 do Imbassa\u00ed, interditando meia pista,<\/p>\n","protected":false},"author":1,"featured_media":15404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-15406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=15406"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15406\/revisions"}],"predecessor-version":[{"id":15407,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15406\/revisions\/15407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/15404"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=15406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=15406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=15406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}