{"id":15513,"date":"2020-10-11T20:29:10","date_gmt":"2020-10-11T23:29:10","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=15513"},"modified":"2020-10-11T20:29:11","modified_gmt":"2020-10-11T23:29:11","slug":"pm-e-guarda-municipal-acabam-com-baile-funk-clandestino-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/10\/11\/pm-e-guarda-municipal-acabam-com-baile-funk-clandestino-em-itaipuacu\/","title":{"rendered":"PM e Guarda Municipal acabam com baile funk clandestino em Itaipua\u00e7u"},"content":{"rendered":"\n<p>Policiais militares da 6\u00aa Cia junto a guardas municipais impediram que acontecesse um baile funk, na Comunidade do Parque Vera Cruz, em Itaipua\u00e7u, na madrugada deste domingo (11).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o baile estava sendo organizado desde cedo, e at\u00e9 uma tenda de circo foi instala.<\/p>\n\n\n\n<p>Os policiais seguiram para o local juntos aos agentes da guarda municipal e deram ordem para que o som fosse desligado. <\/p>\n\n\n\n<p>Nenhum respons\u00e1vel pelo evento clandestino apareceu.<\/p>\n\n\n\n<p>Na sexta-feira, um baile funk foi impedido no Cantinho, em Maric\u00e1. A Pol\u00edcia Militar segue trabalhando para manter a paz na cidade.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares da 6\u00aa Cia junto a guardas municipais impediram que acontecesse um baile funk, na Comunidade do Parque Vera<\/p>\n","protected":false},"author":1,"featured_media":15516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-15513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=15513"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15513\/revisions"}],"predecessor-version":[{"id":15517,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15513\/revisions\/15517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/15516"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=15513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=15513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=15513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}