{"id":15519,"date":"2020-10-11T21:49:40","date_gmt":"2020-10-12T00:49:40","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=15519"},"modified":"2020-10-11T21:49:41","modified_gmt":"2020-10-12T00:49:41","slug":"pm-e-recebida-a-tiros-na-comunidade-risca-faca-em-inoa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/10\/11\/pm-e-recebida-a-tiros-na-comunidade-risca-faca-em-inoa\/","title":{"rendered":"PM \u00e9 recebida a tiros na Comunidade &#8216;Risca Faca&#8217;, em Ino\u00e3"},"content":{"rendered":"\n<p>Policiais Militares da 6\u00aa Companhia de Maric\u00e1 foram recebidos a tiros na noite deste domingo, 11, na Comunidade &#8216;Risca Faca&#8217;, em Ino\u00e3.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, os agentes realizavam um patrulhamento de rotina, por ordem do Capit\u00e3o Thiago Hil\u00e1rio, no intuito de coibir o tr\u00e1fico de drogas na comunidade. Ao entrarem na localidade, os Militares foram recebidos \u00e0 tiros.<\/p>\n\n\n\n<p>Os elementos fugiram mas deixaram para tr\u00e1s uma carga de drogas, contendo coca\u00edna e maconha, que foi apreendida pela Pol\u00edcia Militar. Al\u00e9m das drogas, um r\u00e1dio transmissor tamb\u00e9m foi apreendido.<\/p>\n\n\n\n<p>O material foi levado para a Delegacia de Maric\u00e1, onde o caso foi registrado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais Militares da 6\u00aa Companhia de Maric\u00e1 foram recebidos a tiros na noite deste domingo, 11, na Comunidade &#8216;Risca Faca&#8217;,<\/p>\n","protected":false},"author":1,"featured_media":15523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-15519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=15519"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15519\/revisions"}],"predecessor-version":[{"id":15521,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15519\/revisions\/15521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/15523"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=15519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=15519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=15519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}