{"id":15593,"date":"2020-10-14T08:53:18","date_gmt":"2020-10-14T11:53:18","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=15593"},"modified":"2020-10-14T08:53:18","modified_gmt":"2020-10-14T11:53:18","slug":"caixa-paga-abono-salarial-para-nascidos-em-outubro","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/10\/14\/caixa-paga-abono-salarial-para-nascidos-em-outubro\/","title":{"rendered":"Caixa paga abono salarial para nascidos em outubro"},"content":{"rendered":"\n<p>A Caixa Econ\u00f4mica Federal inicia nesta quarta-feira (14) o pagamento do abono salarial para os trabalhadores nascidos em outubro que ainda n\u00e3o receberam por meio de cr\u00e9dito em conta. Esp\u00e9cie de 14\u00ba sal\u00e1rio pago a trabalhadores formais que recebem at\u00e9 dois sal\u00e1rios m\u00ednimos, o abono salarial varia de R$ 88 a R$ 1.045 conforme o n\u00famero de meses trabalhados com carteira assinada no ano anterior.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1390512&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1390512&amp;o=node\"><\/p>\n\n\n\n<p>Para trabalhadores da iniciativa privada, os valores podem ser sacados com o Cart\u00e3o do Cidad\u00e3o e senha nos terminais de autoatendimento, unidades lot\u00e9ricas e nos correspondentes Caixa Aqui, al\u00e9m das ag\u00eancias. Segundo a Caixa, mais de 731 mil trabalhadores nascidos em outubro t\u00eam direito ao saque do benef\u00edcio, totalizando R$ 565 milh\u00f5es em recursos disponibilizados neste lote.<\/p>\n\n\n\n<p>J\u00e1 para os funcion\u00e1rios p\u00fablicos ou de empresas estatais, vale o d\u00edgito final do n\u00famero de inscri\u00e7\u00e3o do Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico (Pasep). A partir de amanh\u00e3, o benef\u00edcio fica dispon\u00edvel para inscritos com final 3.<\/p>\n\n\n\n<p>Os trabalhadores que nasceram entre julho e dezembro recebem o abono salarial do PIS ainda neste ano. Os nascidos entre janeiro e junho ter\u00e3o o recurso dispon\u00edvel para saque em 2021.<\/p>\n\n\n\n<p>Os servidores p\u00fablicos com o final de inscri\u00e7\u00e3o do Pasep entre 0 e 4 tamb\u00e9m recebem neste ano. J\u00e1 as inscri\u00e7\u00f5es com final entre 5 e 9, em 2021. O fechamento do calend\u00e1rio de pagamento do exerc\u00edcio 2020\/2021 ser\u00e1 em 30 de junho de 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem tem direito<\/h2>\n\n\n\n<p>Tem direito ao abono salarial 2020\/2021 o trabalhador inscrito no Programa de Integra\u00e7\u00e3o Social (PIS) h\u00e1 pelo menos cinco anos e que tenha trabalhado formalmente por pelo menos 30 dias em 2019, com remunera\u00e7\u00e3o mensal m\u00e9dia de at\u00e9 dois sal\u00e1rios m\u00ednimos. Tamb\u00e9m \u00e9 necess\u00e1rio que os dados tenham sido informados corretamente pelo empregador na Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais (RAIS) ou eSocial, conforme categoria da empresa.<\/p>\n\n\n\n<p>Recebem o benef\u00edcio na Caixa os trabalhadores vinculados a entidades e empresas privadas. Em todo o calend\u00e1rio 2020\/2021, a Caixa deve disponibilizar R$ 15,8 bilh\u00f5es para 20,5 milh\u00f5es trabalhadores.<\/p>\n\n\n\n<p>Quem trabalha no setor p\u00fablico tem inscri\u00e7\u00e3o no Pasep e recebem o benef\u00edcio no Banco do Brasil (BB). Nesse caso, o benefici\u00e1rio pode optar por realizar transfer\u00eancia (TED) para conta de mesma titularidade em outras institui\u00e7\u00f5es financeiras nos terminais de autoatendimento do BB ou no portal www.bb.com.br\/pasep, ou ainda efetuar o saque nos caixas das ag\u00eancias.<\/p>\n\n\n\n<p>Para o exerc\u00edcio atual, o BB identificou abono salarial para 2,7 milh\u00f5es de trabalhadores vinculados ao Pasep, totalizando R$ 2,57 bilh\u00f5es. Desse montante, aproximadamente 1,2 milh\u00e3o s\u00e3o correntistas ou poupadores do BB, e aqueles com final de inscri\u00e7\u00e3o de 0 a 4 receberam seus cr\u00e9ditos em conta antecipadamente no dia 30 de junho, no total de R$ 580 milh\u00f5es, segundo a institui\u00e7\u00e3o financeira.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Abono salarial anterior<\/h2>\n\n\n\n<p>Cerca de 2 milh\u00f5es de trabalhadores que n\u00e3o sacaram o abono salarial do calend\u00e1rio anterior (2019\/2020), finalizado em 29 de maio deste ano, ainda podem retirar os valores. O prazo vai at\u00e9 30 de junho de 2021. O saque pode se feito nos canais de atendimento com cart\u00e3o e senha Cidad\u00e3o, ou nas ag\u00eancias da Caixa.<\/p>\n\n\n\n<p>A consulta do direito ao benef\u00edcio, bem como do valor disponibilizado, pode ser realizada por meio do aplicativo Caixa Trabalhador, pelo atendimento Caixa ao Cidad\u00e3o (0800-726-0207) e em\u00a0p\u00e1gina da Caixa.<\/p>\n\n\n\n<p>No caso do Pasep, cerca de 360 mil trabalhadores n\u00e3o sacaram o abono referente ao exerc\u00edcio 2019\/2020, pago at\u00e9 29 de maio deste ano. De acordo com resolu\u00e7\u00e3o do Conselho Deliberativo do Fundo de Amparo ao Trabalhador (Codefat), esses recursos ficam dispon\u00edveis para saque por cinco anos, contados do encerramento do exerc\u00edcio. Os abonos n\u00e3o sacados s\u00e3o disponibilizados automaticamente para o pr\u00f3ximo exerc\u00edcio, sem necessidade de solicita\u00e7\u00e3o do trabalhador. (Ag\u00eancia Brasil)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Caixa Econ\u00f4mica Federal inicia nesta quarta-feira (14) o pagamento do abono salarial para os trabalhadores nascidos em outubro que<\/p>\n","protected":false},"author":1,"featured_media":15594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-15593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=15593"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15593\/revisions"}],"predecessor-version":[{"id":15595,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/15593\/revisions\/15595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/15594"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=15593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=15593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=15593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}