{"id":16303,"date":"2020-11-03T18:01:34","date_gmt":"2020-11-03T21:01:34","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=16303"},"modified":"2020-11-03T18:29:46","modified_gmt":"2020-11-03T21:29:46","slug":"proeis-recupera-motocicleta-e-apreende-radio-transmissor-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/11\/03\/proeis-recupera-motocicleta-e-apreende-radio-transmissor-em-itaipuacu\/","title":{"rendered":"PROEIS recupera motocicleta e apreende r\u00e1dio transmissor em Itaipua\u00e7u"},"content":{"rendered":"\n<p>Policiais militares do Programa Estadual de Integra\u00e7\u00e3o na Seguran\u00e7a (PROEIS) recuperaram uma motocicleta e apreenderam um r\u00e1dio transmissor, na Avenida Carlos Marighella, pr\u00f3ximo a Ponte Quebrada, em Itaipua\u00e7u, no fim da tarde desta ter\u00e7a-feira (03).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, policiais seguiam em um patrulhamento de rotina quando avistaram um homem em uma moto em atitude suspeita. Quando a guarni\u00e7\u00e3o tentou efetuar abordagem o homem fugiu, abandonando a moto metros a frente, seguindo para um terreno baldio. <\/p>\n\n\n\n<p>Na a\u00e7\u00e3o, o homem conseguiu fugir, abandonando um r\u00e1dio transmissor.<\/p>\n\n\n\n<p>A motocicleta e o r\u00e1dio transmissor foram encaminhados para a Delegacia de Maric\u00e1, onde o caso foi registrado. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares do Programa Estadual de Integra\u00e7\u00e3o na Seguran\u00e7a (PROEIS) recuperaram uma motocicleta e apreenderam um r\u00e1dio transmissor, na Avenida<\/p>\n","protected":false},"author":1,"featured_media":16304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-16303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=16303"}],"version-history":[{"count":3,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16303\/revisions"}],"predecessor-version":[{"id":16307,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16303\/revisions\/16307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/16304"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=16303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=16303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=16303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}