{"id":16585,"date":"2020-11-12T16:18:07","date_gmt":"2020-11-12T19:18:07","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=16585"},"modified":"2020-11-12T16:18:09","modified_gmt":"2020-11-12T19:18:09","slug":"obra-em-rua-no-centro-de-marica-gera-reclamacoes-entre-moradores-e-motoristas","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/11\/12\/obra-em-rua-no-centro-de-marica-gera-reclamacoes-entre-moradores-e-motoristas\/","title":{"rendered":"Obra em rua no Centro de Maric\u00e1 gera reclama\u00e7\u00f5es entre moradores e motoristas"},"content":{"rendered":"\n<p>O tr\u00e2nsito de parte do Centro de Maric\u00e1 foi modificado nesta semana, em raz\u00e3o da fase final da a\u00e7\u00e3o de macrodrenagem realizada pela Prefeitura de Maric\u00e1 na Rua Abreu Sodr\u00e9, no trecho entre a rotat\u00f3ria da ponte da Mumbuca e a Pra\u00e7a Conselheiro Macedo Soares. <\/p>\n\n\n\n<p>Nesta manh\u00e3, j\u00e1 estava liberado uma parte do fluxo mas ao longo da semana a via pode ser fechada novamente. A obra persiste no local h\u00e1 semanas e tem gerado diversas reclama\u00e7\u00f5es entre moradores e motoristas. Em raz\u00e3o dos procedimentos, a pista ficou completamente embara\u00e7ada e em dias de chuva, quase intransit\u00e1vel.<\/p>\n\n\n\n<p>Para os moradores, a obra j\u00e1 dura h\u00e1 muito tempo e a rua est\u00e1 em uma situa\u00e7\u00e3o tr\u00e1gica, com muitos buracos, um perigo pois \u00e9 uma via muito movimentada do centro.<\/p>\n\n\n\n<p><br>A obra faz parte das mudan\u00e7as para evitar inunda\u00e7\u00f5es no Centro da cidade. A coloca\u00e7\u00e3o de uma nova rede que vai escoar \u00e1guas pluviais at\u00e9 o rio Mumbuca come\u00e7ou em julho. A galeria \u00e9 composta por estruturas pr\u00e9-moldadas com 2 metros de altura por 4 metros de largura, e que ocupam toda a extens\u00e3o deste trecho da Rua Abreu Sodr\u00e9.<\/p>\n\n\n\n<p><br>A \u00faltima etapa da obra ser\u00e1 a liga\u00e7\u00e3o com a rede que vem do Flamengo, prevista para ocorrer nos pr\u00f3ximos dias. Enquanto isso, homens e m\u00e1quinas ir\u00e3o preparar o novo piso da via, que dever\u00e1 estar pronto at\u00e9 a pr\u00f3xima semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tr\u00e2nsito de parte do Centro de Maric\u00e1 foi modificado nesta semana, em raz\u00e3o da fase final da a\u00e7\u00e3o de<\/p>\n","protected":false},"author":1,"featured_media":16595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-16585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=16585"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16585\/revisions"}],"predecessor-version":[{"id":16596,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16585\/revisions\/16596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/16595"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=16585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=16585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=16585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}