{"id":16980,"date":"2020-11-23T13:39:18","date_gmt":"2020-11-23T16:39:18","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=16980"},"modified":"2020-11-28T19:38:37","modified_gmt":"2020-11-28T22:38:37","slug":"policia-civil-prende-acusado-de-estuprar-criancas-entre-5-e-10-anos-de-idade-em-araruama","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/11\/23\/policia-civil-prende-acusado-de-estuprar-criancas-entre-5-e-10-anos-de-idade-em-araruama\/","title":{"rendered":"Pol\u00edcia Civil prende acusado de estuprar crian\u00e7as entre 5 e 10 anos de idade em Araruama"},"content":{"rendered":"\n<p>Policiais civis da 118\u00aa DP (Araruama) prenderam, na manh\u00e3 deste s\u00e1bado (21), um homem acusado de estuprar crian\u00e7as com idades de 5 e 10 anos. Contra ele foi cumprido mandado de pris\u00e3o pela pr\u00e1tica de estupro de vulner\u00e1vel.<\/p>\n\n\n\n<p>Segundo os agentes, as investiga\u00e7\u00f5es apontam que o criminoso levava as v\u00edtimas para sua casa para brincar com sua filha, que tamb\u00e9m era estuprada por ele. No local, ele praticava todo o tipo de viol\u00eancia sexual contra as crian\u00e7as.<\/p>\n\n\n\n<p>Ainda de acordo com os policiais, o homem j\u00e1 havia sido preso, em 2009, por porte ilegal de arma de fogo de uso restrito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais civis da 118\u00aa DP (Araruama) prenderam, na manh\u00e3 deste s\u00e1bado (21), um homem acusado de estuprar crian\u00e7as com idades<\/p>\n","protected":false},"author":1,"featured_media":16981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-16980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=16980"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16980\/revisions"}],"predecessor-version":[{"id":16982,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/16980\/revisions\/16982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/16981"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=16980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=16980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=16980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}