{"id":17210,"date":"2020-11-29T11:37:16","date_gmt":"2020-11-29T14:37:16","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=17210"},"modified":"2020-11-30T10:26:15","modified_gmt":"2020-11-30T13:26:15","slug":"policia-ambiental-apreende-4-toneladas-de-sardinhas-em-peixaria-de-inoa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/11\/29\/policia-ambiental-apreende-4-toneladas-de-sardinhas-em-peixaria-de-inoa\/","title":{"rendered":"Pol\u00edcia Ambiental apreende 4 toneladas de sardinhas em peixaria de Ino\u00e3"},"content":{"rendered":"\n<p>Policiais militares da Unidade de Policiamento Ambiental (UPAm) da Serra da Tiririca apreenderam no final da tarde deste s\u00e1bado, 28, quatro toneladas de sardinhas em uma peixaria, em Ino\u00e3.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, os agentes passavam pelo local quando avistaram um homem colocando caixas de sardinhas para exposi\u00e7\u00e3o para venda. Os Policiais realizaram a abordagem e o propriet\u00e1rio apresentou notas fiscais e notas de estoque por\u00e9m as sardinhas estavam sendo estocadas de forma inatura.<\/p>\n\n\n\n<p>O caso foi registrado na Delegacia de Maric\u00e1 e as sardinhas foram apreendidas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/11\/IMG-20201129-WA0052.jpg\" alt=\"\" class=\"wp-image-17213\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/11\/IMG-20201129-WA0052.jpg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/11\/IMG-20201129-WA0052-300x300.jpg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/11\/IMG-20201129-WA0052-150x150.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares da Unidade de Policiamento Ambiental (UPAm) da Serra da Tiririca apreenderam no final da tarde deste s\u00e1bado, 28,<\/p>\n","protected":false},"author":1,"featured_media":17212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-17210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/17210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=17210"}],"version-history":[{"count":5,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/17210\/revisions"}],"predecessor-version":[{"id":17228,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/17210\/revisions\/17228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/17212"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=17210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=17210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=17210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}