{"id":19236,"date":"2021-01-19T13:27:31","date_gmt":"2021-01-19T16:27:31","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=19236"},"modified":"2021-02-01T20:18:24","modified_gmt":"2021-02-01T23:18:24","slug":"homem-e-morto-com-8-tiros-na-cabeca-em-araruama","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/01\/19\/homem-e-morto-com-8-tiros-na-cabeca-em-araruama\/","title":{"rendered":"Homem \u00e9 morto com 8 tiros na cabe\u00e7a em Araruama"},"content":{"rendered":"\n<p>Um homem de 25 anos foi morto a tiros na madrugada da \u00faltima segunda-feira (18), na Rua Alegro, localizada no bairro Fonte Limpa, em Araruama. A v\u00edtima utilizava tornozeleira eletr\u00f4nica e era monitorada pela Secretaria de Seguran\u00e7a P\u00fablica do Estado do Rio de Janeiro.&nbsp;<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es da Pol\u00edcia Militar, os policiais foram acionados por vizinhos da v\u00edtima, que ouviram disparos na casa da mesma, que morava sozinha. Ao chegarem ao local, os agentes j\u00e1 encontraram o homem morto com marcas de tiro pelo corpo. Ele possu\u00eda 8 tiros na cabe\u00e7a.<\/p>\n\n\n\n<p>O caso ser\u00e1 investigado pela 118\u00aa DP (Araruama) e o corpo do homem j\u00e1 foi encaminhado para o Instituto M\u00e9dico Legal (IML) de S\u00e3o Gon\u00e7alo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 25 anos foi morto a tiros na madrugada da \u00faltima segunda-feira (18), na Rua Alegro, localizada no<\/p>\n","protected":false},"author":1,"featured_media":19239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-19236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/19236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=19236"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/19236\/revisions"}],"predecessor-version":[{"id":19240,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/19236\/revisions\/19240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/19239"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=19236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=19236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=19236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}