{"id":20597,"date":"2021-02-20T00:48:10","date_gmt":"2021-02-20T03:48:10","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=20597"},"modified":"2021-02-28T01:22:15","modified_gmt":"2021-02-28T04:22:15","slug":"tentativa-de-assalto-termina-com-bandido-preso-na-regiao-central-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/02\/20\/tentativa-de-assalto-termina-com-bandido-preso-na-regiao-central-de-marica\/","title":{"rendered":"Tentativa de assalto termina com bandido preso na Regi\u00e3o Central de Maric\u00e1"},"content":{"rendered":"\n<p>Um criminoso que estava realizando assaltos de Itaipua\u00e7u ao Centro de Maric\u00e1 foi preso no final da noite desta sexta-feira, 19, na Regi\u00e3o Central de Maric\u00e1, no bairro do Flamengo.<\/p>\n\n\n\n<p>O caso aconteceu pr\u00f3ximo ao Cemit\u00e9rio de Maric\u00e1. Segundo informa\u00e7\u00f5es, o bandido roubou um carro de um motorista de aplicativo em Itaipua\u00e7u, na altura da Rua 33, e seguiu rumo ao Centro de Maric\u00e1.<\/p>\n\n\n\n<p>Chegando no Flamengo, o assaltante seguiu um motoboy e o rendeu  pr\u00f3ximo ao seu local de trabalho. A v\u00edtima percebeu que o criminoso  o criminoso estava com uma arma de brinquedo e reagiu ao assalto <\/p>\n\n\n\n<p>Com a ajuda de um outro funcion\u00e1rio da lanchonete, o entregador conseguiu imobilizar o criminoso e acionou a Pol\u00edcia Militar. <\/p>\n\n\n\n<p>Policiais Militares foram ao local e o bandido foi levado para a Delegacia de Maric\u00e1. O carro roubado ser\u00e1 devolvido ao pr\u00f3prietario. Felizmente, ningu\u00e9m ferido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um criminoso que estava realizando assaltos de Itaipua\u00e7u ao Centro de Maric\u00e1 foi preso no final da noite desta sexta-feira,<\/p>\n","protected":false},"author":1,"featured_media":20598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-20597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/20597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=20597"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/20597\/revisions"}],"predecessor-version":[{"id":20599,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/20597\/revisions\/20599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/20598"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=20597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=20597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=20597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}