{"id":22047,"date":"2021-03-26T10:31:24","date_gmt":"2021-03-26T13:31:24","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=22047"},"modified":"2021-03-26T10:31:25","modified_gmt":"2021-03-26T13:31:25","slug":"associacao-de-moradores-e-amigos-de-jacaroa-realiza-votacao-para-nova-diretoria-em-abril","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/03\/26\/associacao-de-moradores-e-amigos-de-jacaroa-realiza-votacao-para-nova-diretoria-em-abril\/","title":{"rendered":"Associa\u00e7\u00e3o de moradores e amigos de Jacaro\u00e1 realiza vota\u00e7\u00e3o para nova diretoria em abril"},"content":{"rendered":"\n<p>Moradores de Jacaro\u00e1 est\u00e3o sendo convocados para participar da assembl\u00e9ia geral da Associa\u00e7\u00e3o de moradores e amigos do bairro no pr\u00f3ximo dia 10 de abril, para vota\u00e7\u00e3o da nova diretoria.<\/p>\n\n\n\n<p>\u00c0s 09:00 horas ser\u00e1 a primeira convoca\u00e7\u00e3o e \u00e0s 10:00horas a \u00faltima convoca\u00e7\u00e3o, independente do quorum.<\/p>\n\n\n\n<p>A assembl\u00e9ia acontecer\u00e1 na Avenida Lagomar, em campo aberto, em frente a Rua Ariel Coelho de Souza. Aten\u00e7\u00e3o as observa\u00e7\u00f5es:<\/p>\n\n\n\n<p>A vota\u00e7\u00e3o ocorrer\u00e1 das 09horas at\u00e9 \u00e0s 13horas impreterivelmente.<br>-Somente poder\u00e3o votar os associados que apresentarem o comprovante de pagamento da mensalidade de Mar\u00e7o\/2021, juntamente com a sua carteira de identidade.<br>-Nesta data ser\u00e1 designada no prazo de 30 dias nova assembl\u00e9ia para tratar de assuntos gerais AMAJ.<br>-A pandemia ainda n\u00e3o acabou portanto todos os participantes devem seguir os protocolos de seguran\u00e7a como o uso de m\u00e1scara, \u00e1lcool em gel e demais divulgados pela Prefeitura de Maric\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moradores de Jacaro\u00e1 est\u00e3o sendo convocados para participar da assembl\u00e9ia geral da Associa\u00e7\u00e3o de moradores e amigos do bairro no<\/p>\n","protected":false},"author":1,"featured_media":22048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-22047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=22047"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22047\/revisions"}],"predecessor-version":[{"id":22049,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22047\/revisions\/22049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/22048"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=22047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=22047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=22047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}