{"id":22130,"date":"2021-03-29T07:22:47","date_gmt":"2021-03-29T10:22:47","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=22130"},"modified":"2021-03-29T07:22:48","modified_gmt":"2021-03-29T10:22:48","slug":"populacao-adere-ao-distanciamento-social-e-deixa-vazias-praias-e-orlas-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/03\/29\/populacao-adere-ao-distanciamento-social-e-deixa-vazias-praias-e-orlas-de-marica\/","title":{"rendered":"Popula\u00e7\u00e3o adere ao distanciamento social e deixa vazias praias e orlas de Maric\u00e1"},"content":{"rendered":"\n<p>A popula\u00e7\u00e3o de Maric\u00e1 sinalizou neste s\u00e1bado (27\/3) que entendeu e apoia a import\u00e2ncia do distanciamento social no mais grave momento da pandemia da Covid-19. Mesmo com o dia de sol e forte calor, os locais que costumam ter grande procura de moradores e visitantes na cidade, como praias as orlas, ficaram vazios durante todo o dia. As barreiras sanit\u00e1rias e bloqueios nos acessos em parte desses locais tamb\u00e9m impediram a chegada de visitantes.<\/p>\n\n\n\n<p>Na Barra de Maric\u00e1, quase todas as ruas tiveram grandes manilhas instaladas nas esquinas com a Avenida Maysa, enquanto as orlas do Boqueir\u00e3o e Z\u00e9 Garoto, que fica ao lado, foram fechadas com grades por equipes da Secretaria de Prote\u00e7\u00e3o e Defesa Civil. Perto dali, agentes da Guarda Municipal e da Secretaria de Tr\u00e2nsito e Engenharia Vi\u00e1ria conferiam comprovantes de resid\u00eancia de motoristas que passavam pela barreira montada na rotat\u00f3ria de Zacarias.<\/p>\n\n\n\n<p>Ao longo da orla desde a Barra at\u00e9 Ponta Negra, n\u00e3o havia procura de banhistas e tamb\u00e9m n\u00e3o se viu o costumeiro movimento de ve\u00edculos, mesmo cen\u00e1rio observado tamb\u00e9m nas areias de Itaipua\u00e7u. As \u00e1guas do canal de Ponta Negra tamb\u00e9m ficaram vazias. Nas orlas de Guaratiba, Itapeba e Ara\u00e7atiba, os brinquedos e aparelhos de gin\u00e1stica receberam fitas de isolamento para impedir a utiliza\u00e7\u00e3o, assim como as mesas de ping-pong.<\/p>\n\n\n\n<p>Equipes da secretaria de Prote\u00e7\u00e3o e Defesa Civil do munic\u00edpio, percorreram &nbsp;a orla do Recanto at\u00e9 Jacon\u00e9 abordando as poucas &nbsp;pessoas que insistiram em descumprir o Decreto Municipal. Elas foram orientadas pelos agentes e deixaram o local.<\/p>\n\n\n\n<p>Bandeira Laranja<\/p>\n\n\n\n<p>Desde a \u00faltima sexta-feira (26\/3), um efetivo de aproximadamente 190 agentes atua nas ruas para garantir o cumprimento das determina\u00e7\u00f5es do decreto anunciado pelo prefeito Fabiano Horta na ter\u00e7a-feira (23), que p\u00f4s a cidade na Bandeira Laranja de preven\u00e7\u00e3o \u00e0 Covid-19. Oito barreiras sanit\u00e1rias foram instaladas em Ponta Negra (pr\u00f3ximo ao acesso a Jacon\u00e9), Bambu\u00ed (na Avenida Ant\u00f4nio Callado), Serra do Lagarto, Ubatiba (junto ao m\u00f3dulo de seguran\u00e7a), Barra de Maric\u00e1 (rotat\u00f3ria de Zacarias) e em tr\u00eas pontos de Itaipua\u00e7u (rotat\u00f3ria da Avenida Gilberto Carvalho, Estrada dos Cajueiros e Recanto).<\/p>\n\n\n\n<p>No Espraiado e na praia da Sacristia (tamb\u00e9m em Ponta Negra) n\u00e3o h\u00e1 essas barreiras, mas o acesso de frequentadores mesmo a p\u00e9 n\u00e3o ser\u00e1 permitido. As tendas com os agentes v\u00e3o funcionar durante o fim de semana e retornam na quinta-feira (01\/04), em raz\u00e3o do feriado da Semana Santa. Nestes per\u00edodos, o acesso s\u00f3 ser\u00e1 permitido se for comprovada a resid\u00eancia no munic\u00edpio. A secretaria de Ordem P\u00fablica e Gabinete Institucional de Maric\u00e1 (Seop) recomenda que mesmo os moradores que n\u00e3o pretendem sair da cidade levem consigo algum comprovante, ainda que os deslocamentos sejam curtos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A popula\u00e7\u00e3o de Maric\u00e1 sinalizou neste s\u00e1bado (27\/3) que entendeu e apoia a import\u00e2ncia do distanciamento social no mais grave<\/p>\n","protected":false},"author":1,"featured_media":22131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-22130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=22130"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22130\/revisions"}],"predecessor-version":[{"id":22132,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22130\/revisions\/22132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/22131"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=22130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=22130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=22130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}