{"id":22411,"date":"2021-04-05T10:07:15","date_gmt":"2021-04-05T13:07:15","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=22411"},"modified":"2021-04-05T10:08:41","modified_gmt":"2021-04-05T13:08:41","slug":"familiares-procuram-por-jovem-desaparecido-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/04\/05\/familiares-procuram-por-jovem-desaparecido-em-marica\/","title":{"rendered":"Familiares procuram por jovem desaparecido em Maric\u00e1"},"content":{"rendered":"\n<p>Familiares procuram por Jo\u00e3o Victor da Rosa Costa Abreu, de 17 anos, desaparecido em Maric\u00e1 desde o dia 01 de abril.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o menor saiu de casa e n\u00e3o voltou mais. Parentes afirmam que o adolescente n\u00e3o tem costume de ficar tanto tempo fora sem dar not\u00edcias. <\/p>\n\n\n\n<p>Quem tiver informa\u00e7\u00f5es  entre em contato pelo n\u00famero 21 2286-8337.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"943\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/04\/167434832_496300471374019_2991483347062556059_n-1.jpg\" alt=\"\" class=\"wp-image-22415\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/04\/167434832_496300471374019_2991483347062556059_n-1.jpg 750w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/04\/167434832_496300471374019_2991483347062556059_n-1-239x300.jpg 239w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familiares procuram por Jo\u00e3o Victor da Rosa Costa Abreu, de 17 anos, desaparecido em Maric\u00e1 desde o dia 01 de<\/p>\n","protected":false},"author":1,"featured_media":22412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-22411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=22411"}],"version-history":[{"count":3,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22411\/revisions"}],"predecessor-version":[{"id":22416,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/22411\/revisions\/22416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/22412"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=22411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=22411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=22411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}