{"id":2286,"date":"2019-07-09T22:41:58","date_gmt":"2019-07-10T01:41:58","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=2286"},"modified":"2019-07-09T22:42:00","modified_gmt":"2019-07-10T01:42:00","slug":"jovens-recebem-dispensa-de-incorporacao-militar-no-cineteatro-henfil","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/07\/09\/jovens-recebem-dispensa-de-incorporacao-militar-no-cineteatro-henfil\/","title":{"rendered":"JOVENS RECEBEM DISPENSA DE INCORPORA\u00c7\u00c3O MILITAR NO CINETEATRO HENFIL"},"content":{"rendered":"\n<p>Uma solenidade realizada nesta ter\u00e7a-feira (09\/07) no Cinema Henfil, no Centro, marcou a entrega dos certificados de dispensa de incorpora\u00e7\u00e3o ao Ex\u00e9rcito Brasileiro para cerca de 100 jovens da cidade. Antes de receber seus documentos, todos fizeram o juramento \u00e0 bandeira, onde prometem estar prontos a qualquer tempo para as obriga\u00e7\u00f5es militares, que incluem convoca\u00e7\u00f5es de emerg\u00eancia.<\/p>\n\n\n\n<p>A cerim\u00f4nia foi comandada pelo chefe do Posto Regional de Recrutamento e Mobiliza\u00e7\u00e3o, tenente-coronel Carlos Alexsandro de Almeida, e pelo delegado do Servi\u00e7o Militar de Maric\u00e1, 1\u00ba tenente Rosan Barbosa de Azevedo.<\/p>\n\n\n\n<p>Na abertura, ap\u00f3s as execu\u00e7\u00f5es dos hinos Nacional Brasileiro e do Expedicion\u00e1rio, foi lido um breve hist\u00f3rico do servi\u00e7o militar no Brasil (que remete ao tempo das capitanias heredit\u00e1rias). Alguns dos jovens subiram ao palco para receber seus certificados das m\u00e3os dos oficiais, mas a maioria foi entregue ao final da cerim\u00f4nia.<\/p>\n\n\n\n<p>Boa parte dos jovens estava acompanhada dos pais, que queriam registrar o momento. \u201cFoi uma escolha dele n\u00e3o estar no Ex\u00e9rcito, por ter outros planos na vida\u201d, explicou o radiologista F\u00e1bio Marcos da Silva, de 46 anos, que mora em Ino\u00e3 e estava com o filho Abner, de 18 anos. \u201cDe fato n\u00e3o era um desejo meu servir, mas foi legal participar\u201d, disse o jovem.<\/p>\n\n\n\n<p>J\u00e1 para o estudante Pedro de Morais Fernandes, de 17 anos, que \u00e9 filho de um tenente do Ex\u00e9rcito e pretende seguir a carreira militar, a solenidade teve uma sensa\u00e7\u00e3o diferente. \u201cAchei bonita, uma coisa honrosa para mim\u201d, afirmou ele ao lado da m\u00e3e, a advogada Vivianne Morais. \u201cEle teve um pai militar j\u00e1 falecido e, para mim, lembrou bastante coisa da minha vida. Foi emocionante e tamb\u00e9m bacana ver esses jovens todos aqui\u201d, ressaltou.<\/p>\n\n\n\n<p>De acordo com o tenente-coronel Alexsandro, o ato pretende despertar a import\u00e2ncia de se estar pronto para o servi\u00e7o da p\u00e1tria. \u201cServe para chamar a aten\u00e7\u00e3o n\u00e3o apenas esses jovens mas tamb\u00e9m o cidad\u00e3o em geral, uma vez que o tempo de disponibilidade para o servi\u00e7o militar vai at\u00e9 os 45 anos\u201d, disse o chefe do Posto de Recrutamento e Mobiliza\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma solenidade realizada nesta ter\u00e7a-feira (09\/07) no Cinema Henfil, no Centro, marcou a entrega dos certificados de dispensa de incorpora\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":2287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-2286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=2286"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/2287"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=2286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=2286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=2286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}