{"id":2344,"date":"2019-07-12T15:39:00","date_gmt":"2019-07-12T18:39:00","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=2344"},"modified":"2019-07-12T19:10:34","modified_gmt":"2019-07-12T22:10:34","slug":"secretario-estadual-de-agricultura-pecuaria-e-pesca-eduardo-lopes-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/07\/12\/secretario-estadual-de-agricultura-pecuaria-e-pesca-eduardo-lopes-em-marica\/","title":{"rendered":"Secret\u00e1rio Estadual de Agricultura, Pecu\u00e1ria e Pesca, Eduardo Lopes em Maric\u00e1"},"content":{"rendered":"\n<p>O Secret\u00e1rio Estadual de Agricultura, Pecu\u00e1ria e Pesca, Eduardo Lopes, esteve na manh\u00e3 desta sexta-feira (12) em Maric\u00e1, para conhecer o projeto de plantio do tomate do tipo cereja, no bairro de Retiro.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3754-1-1024x683.jpg\" alt=\"\" class=\"wp-image-2349\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3754-1-1024x683.jpg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3754-1-300x200.jpg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3754-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Carlos A.<\/figcaption><\/figure>\n\n\n\n<p>A produ\u00e7\u00e3o de tomates cereja foi desenvolvida em Israel, mas aqui em Maric\u00e1 uma estufa de 1.000 metros quadrados tem produ\u00e7\u00e3o anual de 25 toneladas e os produtos, tomate ou piment\u00e3o, s\u00e3o vendidos em muitos supermercados. Toda a tecnologia foi nacionalizada e o projeto tem como objetivo criar cooperativas para pessoas carentes melhorarem suas condi\u00e7\u00f5es de vida.\u00a0As sementes usadas t\u00eam prote\u00e7\u00e3o contra pragas e podem ser aperfei\u00e7oadas com a cria\u00e7\u00e3o do Centro de Tecnologia. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"486\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_20190221_162008558_BURST000_COVER-1024x486.jpg\" alt=\"\" class=\"wp-image-2346\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_20190221_162008558_BURST000_COVER-1024x486.jpg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_20190221_162008558_BURST000_COVER-300x143.jpg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_20190221_162008558_BURST000_COVER-768x365.jpg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_20190221_162008558_BURST000_COVER.jpg 1583w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption> &nbsp;Foto: PAULO CELESTINO <\/figcaption><\/figure>\n\n\n\n<p> Calmon Cozer empreendedor da Tomates do Brasil, busca parceria com entidades visando o trabalho conjunto para o sucesso do projeto. \u201cOs produtos agr\u00edcolas org\u00e2nicos t\u00eam alta porcentagem de lucro, permitindo ao agricultor n\u00e3o s\u00f3 ter bem-estar social como devolver o cr\u00e9dito dado pelo Estado. Cozer \u00e9 um Carioca apaixonado pelo que faz, e como um bom empreendedor vem fazendo um trabalho muito bem realizado com seu amigo Peri, que \u00e9 dono do local aonde acontece o plantio, cuidado e colheita dos tomates.<\/p>\n\n\n\n<p>Junto com Secret\u00e1rio estava tamb\u00e9m o presidente do PRB-Maric\u00e1, o Pastor Mariano dos Santos, que junto com sua equipe vem fazendo trabalhos sociais de grande import\u00e2ncia na cidade de Maric\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3760-1-1024x683.jpg\" alt=\"\" class=\"wp-image-2350\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3760-1-1024x683.jpg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3760-1-300x200.jpg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/07\/IMG_3760-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Carlos A.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio Estadual de Agricultura, Pecu\u00e1ria e Pesca, Eduardo Lopes, esteve na manh\u00e3 desta sexta-feira (12) em Maric\u00e1, para conhecer<\/p>\n","protected":false},"author":1,"featured_media":2345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=2344"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/2345"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=2344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=2344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=2344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}