{"id":24862,"date":"2021-06-07T13:36:24","date_gmt":"2021-06-07T16:36:24","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=24862"},"modified":"2021-06-07T13:36:26","modified_gmt":"2021-06-07T16:36:26","slug":"marica-recebe-novo-lote-de-vacinas-contra-covid-19-calendario-foi-atualizado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/06\/07\/marica-recebe-novo-lote-de-vacinas-contra-covid-19-calendario-foi-atualizado\/","title":{"rendered":"Maric\u00e1 recebe novo lote de vacinas contra Covid-19; calend\u00e1rio foi atualizado"},"content":{"rendered":"\n<p>O munic\u00edpio de Maric\u00e1 recebeu mais doses da vacina contra Covid-19 nesta segunda-feira (07), Ao todo, o munic\u00edpio recebeu 1.205 doses do imunizante Astrazeneca e 1.170 da Pfizer. <\/p>\n\n\n\n<p>O medicamento foi entregue no N\u00facleo Municipal de Imuniza\u00e7\u00e3o Dr. Heitor da Costa Matta, onde ficar\u00e1 armazenado at\u00e9 a utiliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>O atual calend\u00e1rio, atualizado hoje, prev\u00ea a vacina\u00e7\u00e3o de pessoas sem comorbidades por faixa et\u00e1ria, popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua e trabalhadores do transporte a\u00e9reo do aeroporto municipal.<\/p>\n\n\n\n<p>Permanecem no cronograma cidad\u00e3os com comorbidades e defici\u00eancias por faixa et\u00e1ria, al\u00e9m dos profissionais da educa\u00e7\u00e3o p\u00fablica e privada de Maric\u00e1.<\/p>\n\n\n\n<p>\u00c9 importante destacar que aos s\u00e1bados a vacina\u00e7\u00e3o contra a Covid-19 acontece exclusivamente nas unidades volantes de vacina\u00e7\u00e3o, inclusive com repescagem para a primeira dose da vacina.<\/p>\n\n\n\n<p>Para as pessoas com comorbidades \u00e9 indispens\u00e1vel, no ato da vacina\u00e7\u00e3o, al\u00e9m dos documentos de identifica\u00e7\u00e3o, a apresenta\u00e7\u00e3o de laudo ou declara\u00e7\u00e3o ou atestado ou per\u00edcia m\u00e9dica de qualquer data que comprove a comorbidade; resultado de exame de qualquer data que comprove a comorbidade; receita ou prescri\u00e7\u00e3o de medicamentos para o tratamento da comorbidade, datada no ano de 2021ou duas de outros anos e evid\u00eancia f\u00edsica da comorbidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Maric\u00e1 recebeu mais doses da vacina contra Covid-19 nesta segunda-feira (07), Ao todo, o munic\u00edpio recebeu 1.205<\/p>\n","protected":false},"author":1,"featured_media":24863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-24862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=24862"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24862\/revisions"}],"predecessor-version":[{"id":24864,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24862\/revisions\/24864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/24863"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=24862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=24862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=24862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}