{"id":24946,"date":"2021-06-09T07:22:00","date_gmt":"2021-06-09T10:22:00","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=24946"},"modified":"2021-06-09T07:22:02","modified_gmt":"2021-06-09T10:22:02","slug":"marica-tera-campanha-de-doacao-de-sangue-no-proximo-sabado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/06\/09\/marica-tera-campanha-de-doacao-de-sangue-no-proximo-sabado\/","title":{"rendered":"Maric\u00e1 ter\u00e1 campanha de doa\u00e7\u00e3o de sangue no pr\u00f3ximo s\u00e1bado"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, atrav\u00e9s da Secretaria de Sa\u00fade, realiza, em parceria com o Instituto Estadual de Hematologia Arthur de Siqueira Cavalcanti (Hemorio),&nbsp;no s\u00e1bado (12\/06), uma campanha de doa\u00e7\u00e3o de sangue na cidade. O local da coleta ser\u00e1 o CEM Joana Benedicta Rangel (Centro), no per\u00edodo das 10h \u00e0s 15h.&nbsp;\u00c9 obrigat\u00f3rio o uso de m\u00e1scaras e dever\u00e1 ser mantido distanciamento social de no m\u00ednimo 2 metros em preven\u00e7\u00e3o \u00e0 Covid-19.<\/p>\n\n\n\n<p>Para ser um doador de sangue \u00e9 necess\u00e1rio ter entre 16 e 69 anos, peso acima de 50 kg e estar se sentindo bem de sa\u00fade. N\u00e3o poder\u00e1 ser doador quem teve hepatite depois de 11 anos de idade, quem tem doen\u00e7a transmiss\u00edvel pelo sangue (como aids, hepatite, s\u00edfilis e doen\u00e7a de chagas), gr\u00e1vidas ou lactantes.<\/p>\n\n\n\n<p>Como medida de precau\u00e7\u00e3o contra a Covid-19, a Anvisa orienta que infectados pela Covid-19, ap\u00f3s diagn\u00f3stico cl\u00ednico e\/ou laboratorial, dever\u00e3o ser considerados inaptos a doarem sangue por um per\u00edodo de 30 dias ap\u00f3s a completa recupera\u00e7\u00e3o. Al\u00e9m de quem teve contato, nos \u00faltimos 30 dias, com pessoas que apresentaram diagn\u00f3sticos cl\u00ednicos e ou laboratoriais. Est\u00e1 inapto tamb\u00e9m quem permanece em isolamento volunt\u00e1rio ou indicado por equipe m\u00e9dica devido a sintomas de poss\u00edvel infec\u00e7\u00e3o pela Covid-19 pelo per\u00edodo que durar o isolamento (no m\u00ednimo 14 dias) se estiver assintom\u00e1tico.<\/p>\n\n\n\n<p>\u201cA Campanha de Doa\u00e7\u00e3o de Sangue \u00e9 muito importante porque n\u00f3s tivemos uma queda significativa de doa\u00e7\u00f5es durante o per\u00edodo de pandemia, entretanto n\u00e3o reduziram o n\u00famero de acidentes, nem das diversas necessidades, que continuam crescendo, para atender \u00e0 popula\u00e7\u00e3o. Ent\u00e3o, os bancos de sangue reduzem sua capacidade e se torna imperativo repor esses volumes. A doa\u00e7\u00e3o de sangue \u00e9 essencial e salva vidas!\u201d, observa a secret\u00e1ria de Sa\u00fade, Simone Costa.<\/p>\n\n\n\n<p>O coordenador de Humaniza\u00e7\u00e3o da Rede de Urg\u00eancia e Emerg\u00eancia do munic\u00edpio, Jess\u00e9 Paz, organizador do evento, destacou o fato de estar atento \u00e0s restri\u00e7\u00f5es da doa\u00e7\u00e3o, para evitar a forma\u00e7\u00e3o de aglomera\u00e7\u00f5es no local.<\/p>\n\n\n\n<p>\u201cTodos que tiverem o desejo de doar sangue e ajudar com a campanha precisam ler com aten\u00e7\u00e3o os panfletos e todos os materiais de divulga\u00e7\u00e3o para que n\u00e3o compare\u00e7am ao local sem estarem aptos a doar\u201d, ressaltou Jess\u00e9.<\/p>\n\n\n\n<p>No dia da doa\u00e7\u00e3o, n\u00e3o \u00e9 permitido estar em jejum, nem ingerir qualquer tipo de bebida alc\u00f3olica. O doador precisa dormir, na&nbsp;noite anterior, no m\u00ednimo seis horas, evitar ingerir alimentos gordurosos e fumar por pelo menos duas horas antes. Ser\u00e1 fundamental a apresenta\u00e7\u00e3o de documento com foto, emitido por \u00f3rg\u00e3o oficial e v\u00e1lido em todo o territ\u00f3rio nacional.<\/p>\n\n\n\n<p>O CEM Joana Benedicta Rangel fica na Avenida Nossa Senhora do Amparo, n\u00ba 240, no Centro de Maric\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, atrav\u00e9s da Secretaria de Sa\u00fade, realiza, em parceria com o Instituto Estadual de Hematologia Arthur de<\/p>\n","protected":false},"author":1,"featured_media":24947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-24946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=24946"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24946\/revisions"}],"predecessor-version":[{"id":24948,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/24946\/revisions\/24948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/24947"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=24946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=24946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=24946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}