{"id":25268,"date":"2021-06-17T12:32:25","date_gmt":"2021-06-17T15:32:25","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=25268"},"modified":"2021-06-17T15:07:21","modified_gmt":"2021-06-17T18:07:21","slug":"carros-se-envolvem-em-grave-acidente-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/06\/17\/carros-se-envolvem-em-grave-acidente-em-itaipuacu\/","title":{"rendered":"Carros se envolvem em grave acidente em Itaipua\u00e7u"},"content":{"rendered":"\n<p><br>Tr\u00eas carros se envolverem em um grave acidente na Rua 32 com a Rua 66, no Jardim Atl\u00e2ntico, em Itaipua\u00e7u, no fim da manh\u00e3 desta quinta-feira (17).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es de populares, o motorista da Uno Vivace vinha em alta velocidade quando cruzou a pista e colidiu com a Fiat P\u00e1lio que vinha pela 66 e o Ford KA que estava parado no cruzamento.<\/p>\n\n\n\n<p>Com o impacto da batida, o motorista da Fiat P\u00e1lio sofreu algumas escoria\u00e7\u00f5es pelo corpo.<\/p>\n\n\n\n<p>O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia e Bombeiros do Destacamento de Maric\u00e1 foram acionados para o local e prestaram os primeiros socorros para a v\u00edtima. Em seguida, o homem foi encaminhado para o Hospital Municipal, no Centro. <\/p>\n\n\n\n<p>Policiais militares estiveram no local e registraram a ocorr\u00eancia.<\/p>\n\n\n\n<p>Populares pedem quebra-molas, sinaliza\u00e7\u00e3o e faixa de pedestres para v\u00e1rios cruzamentos do bairro, onde acontecem acidentes constantemente.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas carros se envolverem em um grave acidente na Rua 32 com a Rua 66, no Jardim Atl\u00e2ntico, em Itaipua\u00e7u,<\/p>\n","protected":false},"author":1,"featured_media":25269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-25268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/25268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=25268"}],"version-history":[{"count":5,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/25268\/revisions"}],"predecessor-version":[{"id":25287,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/25268\/revisions\/25287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/25269"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=25268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=25268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=25268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}