{"id":2580,"date":"2019-07-29T08:51:50","date_gmt":"2019-07-29T11:51:50","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=2580"},"modified":"2019-07-29T08:51:53","modified_gmt":"2019-07-29T11:51:53","slug":"homem-em-situacao-de-rua-surta-mata-duas-pessoas-e-cinco-ficam-feridas-no-rio","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/07\/29\/homem-em-situacao-de-rua-surta-mata-duas-pessoas-e-cinco-ficam-feridas-no-rio\/","title":{"rendered":"HOMEM EM SITUA\u00c7\u00c3O DE RUA SURTA, MATA DUAS PESSOAS E CINCO FICAM FERIDAS NO RIO"},"content":{"rendered":"\n<p>Um homem em situa\u00e7\u00e3o de rua esfaqueou e matou duas pessoas na manh\u00e3 deste domingo (28), na Lagoa Rodrigo de Freitas, sob o viaduto Saint Hilaire, na zona sul do Rio, que d\u00e1 acesso ao T\u00fanel Rebou\u00e7as. A informa\u00e7\u00e3o foi divulgada primeiramente pelo jornal Extra.<\/p>\n\n\n\n<p>Segundo a Pol\u00edcia, ap\u00f3s um surto, o suspeito abordou o motorista Jo\u00e3o F\u00e9lix de Carvalho, de 34 anos, com uma faca, por volta de meio-dia. Jo\u00e3o F\u00e9lix chegou a ser levado para o Hospital Municipal Miguel Couto, na G\u00e1vea, mas n\u00e3o resistiu.&nbsp;<\/p>\n\n\n\n<p>Outra v\u00edtima fatal foi identificado como Marcelo Correia, de 39 anos. Ele passava pela Lagoa no momento do ataque e tentou segurar o esfaqueador, que ainda n\u00e3o foi identificado, segundo a Pol\u00edcia Civil.<\/p>\n\n\n\n<p>A namorada de Jo\u00e3o F\u00e9lix, que no momento do ataque estava no banco do carona, tamb\u00e9m foi atingida em uma das m\u00e3os e no quadril. Ela foi socorrida e o estado de sa\u00fade \u00e9 est\u00e1vel.<\/p>\n\n\n\n<p>Enquanto socorria as v\u00edtimas, uma t\u00e9cnica de enfermagem dos Bombeiros tamb\u00e9m acabou baleada em uma das pernas e um m\u00e9dico dos Bombeiros foi atingido por estilha\u00e7os. Os dois foram socorridos e tamb\u00e9m n\u00e3o correm risco de morte.<\/p>\n\n\n\n<p>Uma mulher que passava pelo local e tamb\u00e9m tentou ajudar o motorista, tamb\u00e9m acabou ferida pelo suspeito. Ela foi atendida no local e liberada na sequ\u00eancia.<\/p>\n\n\n\n<p><strong>A\u00e7\u00e3o<\/strong>&nbsp;<\/p>\n\n\n\n<p>Segundo testemunhas, policiais militares chegaram logo em seguida ao ataque e tentaram fazer com que o homem entregasse a faca. Ap\u00f3s a negativa do suspeito, os agentes usaram arma de choque, sem sucesso. O suspeito foi em dire\u00e7\u00e3o aos policiais, que acabaram baleando o homem na perna e um tiro de rasp\u00e3o na cabe\u00e7a. A a\u00e7\u00e3o foi acompanhada por PMs do 23\u00ba BPM (Leblon) e do BPTur.<\/p>\n\n\n\n<p>Na ocasi\u00e3o, um policial militar foi ferido por disparos de arma de fogo que, segundo a DH, vieram de outro agente que estava pr\u00f3ximo e tamb\u00e9m tentava impedir que o suspeito fizesse mais v\u00edtimas.&nbsp;<\/p>\n\n\n\n<p>Ap\u00f3s ser socorrido, o suspeito dizia coisas desconexas e n\u00e3o corre risco de morte. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre o estado de sa\u00fade das outras v\u00edtimas.<\/p>\n\n\n\n<p>O caso est\u00e1 com a Delegacia de Homic\u00eddios da capital (DH).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem em situa\u00e7\u00e3o de rua esfaqueou e matou duas pessoas na manh\u00e3 deste domingo (28), na Lagoa Rodrigo de<\/p>\n","protected":false},"author":1,"featured_media":2581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=2580"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/2581"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=2580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=2580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=2580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}