{"id":26206,"date":"2021-07-10T12:57:46","date_gmt":"2021-07-10T15:57:46","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=26206"},"modified":"2021-07-10T12:57:47","modified_gmt":"2021-07-10T15:57:47","slug":"prefeitura-assina-contrato-de-compra-da-casa-maysa-nesta-terca-feira-13-07","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/07\/10\/prefeitura-assina-contrato-de-compra-da-casa-maysa-nesta-terca-feira-13-07\/","title":{"rendered":"Prefeitura assina contrato de compra da casa Maysa nesta ter\u00e7a-feira (13\/07)"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1 e a Companhia de Desenvolvimento de Maric\u00e1 (Codemar) realizam na pr\u00f3xima ter\u00e7a-feira (13\/07) a cerim\u00f4nia de assinatura de aquisi\u00e7\u00e3o da casa que pertenceu \u00e0 cantora Maysa Matarazzo. A resid\u00eancia, localizada na Praia de Cordeirinho, ser\u00e1 transformada em um Museu Casa. A solenidade contar\u00e1 com a presen\u00e7a do prefeito Fabiano Horta, do presidente da Codemar, Olavo Noleto, do secret\u00e1rio de Cultura, Sady Bianchin e do diretor de cinema e filho da cantora, Jayme Monjardim.<\/p>\n\n\n\n<p>Entre os objetos que compor\u00e3o o acervo est\u00e3o as centenas de cartas manuscritas que falam desde amor a desabafos, letras de m\u00fasicas escritas em guardanapo, fotos, pinturas, m\u00fasicas que n\u00e3o foram gravadas, pintura de quadros, publica\u00e7\u00f5es de jornais da \u00e9poca, entre outros objetos.<\/p>\n\n\n\n<p>Jayme Monjardim classificou a a\u00e7\u00e3o como a realiza\u00e7\u00e3o de um sonho em poder transformar o im\u00f3vel em um Museu Casa.<\/p>\n\n\n\n<p>\u201cPara mim, vai ser um momento muito importante para quem gosta da Maysa, vive a Maysa e para quem \u00e9 f\u00e3 da Maysa. Acho que esse vai ser um espa\u00e7o que n\u00e3o \u00e9 s\u00f3 dela, mas da m\u00fasica brasileira. \u00c9 um espa\u00e7o que a gente vai ter as sensa\u00e7\u00f5es de estar ao lado da Maysa. \u00c9 a realiza\u00e7\u00e3o de um sonho\u201d, afirmou Monjardim.<\/p>\n\n\n\n<p>O Museu Casa Maysa, assim como a casa Beth Carvalho \u2013 cuja assinatura da aquisi\u00e7\u00e3o do im\u00f3vel ocorreu no m\u00eas passado \u2013 e a Casa Darcy Ribeiro, comp\u00f5e o circuito de museus do projeto Caminho das Artes.<\/p>\n\n\n\n<p>\u201cUma das coisas mais importantes \u00e9 essa iniciativa de Maric\u00e1 de criar o circuito cultural, que para mim \u00e9 uma das coisas mais importantes que Maric\u00e1 est\u00e1 fazendo. S\u00e3o poucas as pessoas que t\u00eam essas iniciativas e essa preocupa\u00e7\u00e3o com a cultura do Brasil e com a mem\u00f3ria brasileira. \u00c9 um momento muito importante compartilhar com a Prefeitura e com Maric\u00e1 desse circuito cultural e incluir a casa da Maysa. Para mim, \u00e9 muito importante essa atitude\u201d, disse o diretor de cinema.<\/p>\n\n\n\n<p>Para o presidente da Codemar, Olavo Noleto, a compra da casa Maysa \u00e9 um grande passo para fortalecer o projeto Caminho das Artes. \u201cQuando estiver pronto, o Museu Casa Maysa vai ser um grande destino tur\u00edstico do Rio de Janeiro. Junto com as casas Beth Carvalho, Darcy Ribeiro, Museu do Futebol Jo\u00e3o Saldanha, Cine Henfil e outros aparelhos culturais e tur\u00edsticos que n\u00f3s teremos em Maric\u00e1, elevar\u00e1 a cidade para um outro patamar tur\u00edstico no Brasil e no mundo\u201d, comentou.<\/p>\n\n\n\n<p>A casa Maysa foi constru\u00edda em estilo grego e projetada pelo cen\u00f3grafo Gianni Rato, que a dividiu em tr\u00eas planos: plano da realidade e do territ\u00f3rio; o plano da mem\u00f3ria e o plano do sonho.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio de cultura, Sady Bianchin, o espa\u00e7o vai ser o legado do talento que foi a Maysa.<\/p>\n\n\n\n<p>\u201cEla foi uma pessoa respons\u00e1vel por revitalizar a MPB e, al\u00e9m do mais, foi uma cantora de personalidade e atitude. Isso, enquanto secret\u00e1rio de cultura, me deixa muito feliz e \u00e9 um enorme prazer porque a secretaria tem como prioridade a pluralidade, a quest\u00e3o human\u00edstica e, principalmente, a quest\u00e3o da diversidade cultural. A Maysa \u00e9 um simb\u00f3lico de representa\u00e7\u00e3o desses valores sociais da nossa m\u00fasica\u201d, concluiu.<\/p>\n\n\n\n<p><strong>Servi\u00e7o:&nbsp;<\/strong><\/p>\n\n\n\n<p>Assinatura de aquisi\u00e7\u00e3o da Casa da cantora Maysa que ser\u00e1 transformado em um Museu Casa<\/p>\n\n\n\n<p>Hora: 15h30<\/p>\n\n\n\n<p>Endere\u00e7o: Rua Santa Sofia, antiga Rua 89, Cordeirinho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1 e a Companhia de Desenvolvimento de Maric\u00e1 (Codemar) realizam na pr\u00f3xima ter\u00e7a-feira (13\/07) a cerim\u00f4nia de<\/p>\n","protected":false},"author":1,"featured_media":26207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-26206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/26206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=26206"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/26206\/revisions"}],"predecessor-version":[{"id":26208,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/26206\/revisions\/26208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/26207"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=26206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=26206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=26206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}