{"id":27084,"date":"2021-07-29T13:13:06","date_gmt":"2021-07-29T16:13:06","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=27084"},"modified":"2021-07-29T13:41:49","modified_gmt":"2021-07-29T16:41:49","slug":"vereador-dr-felipe-auni-protocola-projeto-para-reduzir-acidentes-em-cruzamentos-de-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/07\/29\/vereador-dr-felipe-auni-protocola-projeto-para-reduzir-acidentes-em-cruzamentos-de-itaipuacu\/","title":{"rendered":"Vereador Dr. Felipe Auni protocola indica\u00e7\u00e3o para reduzir acidentes em cruzamentos de Itaipua\u00e7u"},"content":{"rendered":"\n<p>O vereador Dr. Felipe Auni protocolou uma indica\u00e7\u00e3o na C\u00e2mara Municipal de Maric\u00e1 nesta quarta-feira (28) para diminuir acidentes nos cruzamentos do bairro de Itaipua\u00e7u, em Maric\u00e1.<\/p>\n\n\n\n<p>O pol\u00edtico solicitou em car\u00e1ter de urg\u00eancia que seja providenciado a sinaliza\u00e7\u00e3o de tr\u00e2nsito horizontal (pintura no asfalto) em todos os cruzamentos das vias movimentadas do Jardim Atl\u00e2ntico.<\/p>\n\n\n\n<p>&#8221;Tal justifica\u00e7\u00e3o motiva-se no fato de proporcionarmos maior infraestrutura no referido bairro. Vale ressaltar, que com a sinaliza\u00e7\u00e3o horizontal ser\u00e1 poss\u00edvel melhor orienta\u00e7\u00e3o aos motoristas e ser\u00e1 evitado in\u00fameros acidentes que vem acontecendo na localidade. Portanto, visando atender os anseios da nossa popula\u00e7\u00e3o, solicito que a presente indica\u00e7\u00e3o seja de imediato encaminhado ao Poder Executivo Municipal para que se torne as devidas provid\u00eancias.&#8221; concluiu Auni. <\/p>\n\n\n\n<p>O bairro de Itaipua\u00e7u vem sofrendo com graves acidentes em v\u00e1rios cruzamentos, na maioria das vezes fatais. A indica\u00e7\u00e3o \u00e9 extremamente importante para que isso diminua ao longo do tempo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador Dr. Felipe Auni protocolou uma indica\u00e7\u00e3o na C\u00e2mara Municipal de Maric\u00e1 nesta quarta-feira (28) para diminuir acidentes nos<\/p>\n","protected":false},"author":1,"featured_media":27085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-27084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=27084"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27084\/revisions"}],"predecessor-version":[{"id":27088,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27084\/revisions\/27088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/27085"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=27084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=27084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=27084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}