{"id":2714,"date":"2019-08-06T12:59:29","date_gmt":"2019-08-06T15:59:29","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=2714"},"modified":"2019-08-06T12:59:31","modified_gmt":"2019-08-06T15:59:31","slug":"policia-resgata-bebe-que-foi-abandonado-dentro-de-uma-bolsa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/08\/06\/policia-resgata-bebe-que-foi-abandonado-dentro-de-uma-bolsa\/","title":{"rendered":"POL\u00cdCIA RESGATA BEB\u00ca QUE FOI ABANDONADO DENTRO DE UMA BOLSA"},"content":{"rendered":"\n<p>Policiais do 18\u00baBPM (Jacarepagu\u00e1) resgataram uma beb\u00ea rec\u00e9m-nascida, na manh\u00e3 desta ter\u00e7a-feira (6), em Curicica, na Zona Oeste do Rio. A crian\u00e7a havia sido abandonada dentro de uma bolsa.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, uma pessoa que estava seguindo para trabalhar viu o beb\u00ea abandonado e ligou para a pol\u00edcia. Os PMs se deslocaram rapidamente para o local, na Rua Floreal, e conseguiram resgatar o beb\u00ea com vida.<\/p>\n\n\n\n<p>A menina foi levada para a Unidade de Pronto Atendimento (UPA) da Taquara. A crian\u00e7a, que ainda estava com o cord\u00e3o umbilical, tem 43 cm, 3,375 kg e est\u00e1 saud\u00e1vel.<\/p>\n\n\n\n<p>O caso foi registrado na 32\u00aaDP (Jacarepagu\u00e1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais do 18\u00baBPM (Jacarepagu\u00e1) resgataram uma beb\u00ea rec\u00e9m-nascida, na manh\u00e3 desta ter\u00e7a-feira (6), em Curicica, na Zona Oeste do Rio.<\/p>\n","protected":false},"author":1,"featured_media":2716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/2716"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}