{"id":27187,"date":"2021-08-02T06:49:06","date_gmt":"2021-08-02T09:49:06","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=27187"},"modified":"2021-08-02T06:49:07","modified_gmt":"2021-08-02T09:49:07","slug":"marica-recebe-5-750-doses-e-retoma-vacinacao-por-idade","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/08\/02\/marica-recebe-5-750-doses-e-retoma-vacinacao-por-idade\/","title":{"rendered":"Maric\u00e1 recebe 5.750 doses e retoma vacina\u00e7\u00e3o por idade"},"content":{"rendered":"\n<p>Maric\u00e1 recebeu neste s\u00e1bado (31\/07) 5.750 doses de vacina contra a Covid-19, entre elas 600 doses do imunizante AstraZeneca (D2), 2.340 de&nbsp;&nbsp;Coronavac&nbsp;(D1 e D2) e 2.720 doses do imunizante da Pfizer (D1). Com a chegada do novo lote,&nbsp;a Secretaria de Sa\u00fade retomar\u00e1 a vacina\u00e7\u00e3o por idades na primeira dose nesta segunda-feira (02\/08). Com isso, ser\u00e3o vacinadas pessoas com 33 anos ou mais.&nbsp; A novidade da primeira semana de agosto \u00e9 que a Prefeitura imunizar\u00e1, tamb\u00e9m com primeira dose, adolescentes entre 12 e 17 anos com comorbidades e defici\u00eancias permanentes, seguindo a orienta\u00e7\u00e3o do Plano Nacional de Imuniza\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Para imunizar os adolescentes ser\u00e1 aplicada a vacina da Pfizer, \u00fanica aprovada pela Anvisa para&nbsp;a&nbsp;faixa de 12&nbsp;a&nbsp;17 anos com comorbidade.&nbsp;A aplica\u00e7\u00e3o acontecer\u00e1 exclusivamente em dois pontos:&nbsp;na&nbsp;Escola Especial&nbsp;Rynalda&nbsp;Rodrigues da Silva, localizada na Rua Vereador Lu\u00eds Ant\u00f4nio da Cunha, no Centro e em&nbsp;Itaipua\u00e7u, na Escola Marqu\u00eas de Maric\u00e1, na Rua 83, no hor\u00e1rio das 09h \u00e0s 16h, onde s\u00e3o aplicadas segunda&nbsp;doses dos imunizantes e tamb\u00e9m a vacina contra a gripe (Influenza).&nbsp;<\/p>\n\n\n\n<p>Segundo a secret\u00e1ria de Sa\u00fade do munic\u00edpio, Solange Oliveira, os respons\u00e1veis pelos adolescentes devem apresentar documento de identifica\u00e7\u00e3o do menor. \u201cComo nas comorbidades teremos menores de idade, \u00e9 preciso que a parte documental deles esteja muito clara. At\u00e9 porque dever\u00e1 ter um respons\u00e1vel que dever\u00e1 apresentar um documento de identifica\u00e7\u00e3o desses menores. Tamb\u00e9m precisa ter em m\u00e3os um comprovante de resid\u00eancia\u201d, explica a secret\u00e1ria, lembrando ainda que \u00e9 preciso estar com o Cart\u00e3o do SUS e com o CPF.&nbsp;<\/p>\n\n\n\n<p>De acordo com a Secretaria de Sa\u00fade, o objetivo de destacar os dois polos para estas categorias \u00e9 para evitar poss\u00edveis aglomera\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p>Com a atualiza\u00e7\u00e3o do calend\u00e1rio de vacina\u00e7\u00e3o, a partir de ter\u00e7a-feira (03\/08) recebem a primeira dose do imunizante pessoas com 32 anos ou mais, e na quarta-feira (04\/08) pessoas com 31 anos ou mais.&nbsp;<\/p>\n\n\n\n<p>Servi\u00e7o: Calend\u00e1rio de vacina\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Adolescentes de 12 a 17 anos com comorbidades: Escola Especial&nbsp;Rynalda&nbsp;Rodrigues da Silva, localizada na Rua Vereador Lu\u00eds Ant\u00f4nio da Cunha, no Centro e em&nbsp;Itaipua\u00e7u, na Escola Marqu\u00eas de Maric\u00e1, na Rua 83(ao lado do Posto de Sa\u00fade Santa Rita).&nbsp;<\/p>\n\n\n\n<p>Documentos necess\u00e1rios: Documento com foto do menor, comprovante de resid\u00eancia, cart\u00e3o SUS, CPF, documento de identidade do respons\u00e1vel.&nbsp;<\/p>\n\n\n\n<p>Hor\u00e1rio: 09h \u00e0s 16h&nbsp;<\/p>\n\n\n\n<p>Pessoas com 33 anos ou mais: Segunda-feira (02\/08)&nbsp;<\/p>\n\n\n\n<p>Pessoas com 32 anos ou mais: Ter\u00e7a-feira (03\/08)&nbsp;<\/p>\n\n\n\n<p>Pessoas com 31 anos ou mais: Quarta-feira (04\/08)&nbsp;<\/p>\n\n\n\n<p>Pontos de vacina\u00e7\u00e3o:&nbsp;USF Jardim Atl\u00e2ntico; USF Ch\u00e1caras de&nbsp;Ino\u00e3; USF&nbsp;Marinel\u00e2ndia; UVV (Unidade Volante de Vacina\u00e7\u00e3o) do Centro Administrativo de&nbsp;Itaipua\u00e7u; UVV Aeroporto de Maric\u00e1;&nbsp;<\/p>\n\n\n\n<p>Hor\u00e1rio de funcionamento: Segunda a sexta-feira, das 09h e 16h.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maric\u00e1 recebeu neste s\u00e1bado (31\/07) 5.750 doses de vacina contra a Covid-19, entre elas 600 doses do imunizante AstraZeneca (D2),<\/p>\n","protected":false},"author":1,"featured_media":27188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-27187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=27187"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27187\/revisions"}],"predecessor-version":[{"id":27189,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27187\/revisions\/27189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/27188"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=27187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=27187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=27187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}