{"id":27901,"date":"2021-08-21T09:34:06","date_gmt":"2021-08-21T12:34:06","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=27901"},"modified":"2021-08-21T09:34:07","modified_gmt":"2021-08-21T12:34:07","slug":"assaltantes-sao-presos-pela-pm-em-inoa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/08\/21\/assaltantes-sao-presos-pela-pm-em-inoa\/","title":{"rendered":"Assaltantes s\u00e3o presos pela PM em Ino\u00e3"},"content":{"rendered":"\n<p>Dois homens que assaltaram v\u00e1rias pessoas foram presos pela Pol\u00edcia Militar, em Ino\u00e3, na manh\u00e3 deste s\u00e1bado (21).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, simulando estarem armados com um cigarro eletr\u00f4nico, a dupla assaltou v\u00e1rias pessoas no Spar e em Ino\u00e3.<\/p>\n\n\n\n<p>Policiais militares do DPO de Ino\u00e3 montaram um certo e conseguiram enquadrar os homens, que estavam em um Sandero de cor prata e placa QOH-8I50.<\/p>\n\n\n\n<p>Dentro do ve\u00edculo foram encontrados v\u00e1rios aparelhos celulares roubados pelos criminosos.<\/p>\n\n\n\n<p>Os homens foram presos e encaminhados para a 82\u00aa DP (Maric\u00e1), onde o caso foi registrado. A dupla ser\u00e1 enquadrada no artigo 157.<\/p>\n\n\n\n<p>O carro usado para cometer os crimes foi alugado para ser usado como uber, o que n\u00e3o aconteceu.\u00a0<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois homens que assaltaram v\u00e1rias pessoas foram presos pela Pol\u00edcia Militar, em Ino\u00e3, na manh\u00e3 deste s\u00e1bado (21). Segundo informa\u00e7\u00f5es,<\/p>\n","protected":false},"author":1,"featured_media":27902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-27901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=27901"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27901\/revisions"}],"predecessor-version":[{"id":27904,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27901\/revisions\/27904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/27902"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=27901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=27901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=27901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}