{"id":27930,"date":"2021-08-23T12:50:26","date_gmt":"2021-08-23T15:50:26","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=27930"},"modified":"2021-08-23T12:52:11","modified_gmt":"2021-08-23T15:52:11","slug":"clima-ensolarado-segue-em-marica-e-temperatura-pode-ultrapassar-os-36-graus","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/08\/23\/clima-ensolarado-segue-em-marica-e-temperatura-pode-ultrapassar-os-36-graus\/","title":{"rendered":"Clima ensolarado segue em Maric\u00e1 e temperatura pode ultrapassar os 36 graus"},"content":{"rendered":"\n<p>Depois de semanas com baixas temperaturas, o calor chegou ao munic\u00edpio de Maric\u00e1 neste final de semana e ir\u00e1 permanecer.<\/p>\n\n\n\n<p>Segundo o Climatempo, hoje, ter\u00e7a-feira e quarta, o tempo permanece limpo com forte calor, registrando 34\u00baC, podendo ultrapassar os 36\u00baC.&nbsp;<\/p>\n\n\n\n<p>Na quinta e na sexta-feira, nuvens chegam ao munic\u00edpio com possibilidade de pancadas de chuva \u00e0 tarde e de noite. O sol aparecer\u00e1 forte e a temperatura fica entre 21\u00baC e 34\u00baC.<\/p>\n\n\n\n<p>No s\u00e1bado, o sol aparece mais forte, mas podendo chover a qualquer momento do dia. No domingo, o sol volta a aparecer com for\u00e7a sem nuvens e chuva. A temperatura varia entre 21\u00baC e 27\u00baC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de semanas com baixas temperaturas, o calor chegou ao munic\u00edpio de Maric\u00e1 neste final de semana e ir\u00e1 permanecer.<\/p>\n","protected":false},"author":1,"featured_media":27931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-27930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=27930"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27930\/revisions"}],"predecessor-version":[{"id":27933,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/27930\/revisions\/27933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/27931"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=27930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=27930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=27930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}