{"id":28937,"date":"2021-09-21T00:44:48","date_gmt":"2021-09-21T03:44:48","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=28937"},"modified":"2021-09-21T08:55:17","modified_gmt":"2021-09-21T11:55:17","slug":"prefeitura-realiza-acolhimento-em-saude-mental-na-praca-do-turismo","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/09\/21\/prefeitura-realiza-acolhimento-em-saude-mental-na-praca-do-turismo\/","title":{"rendered":"Prefeitura realiza acolhimento em sa\u00fade mental na Pra\u00e7a do Turismo"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria Municipal de Sa\u00fade, promoveu nesta segunda-feira (20\/09) o primeiro dia da A\u00e7\u00e3o de Preven\u00e7\u00e3o ao Suic\u00eddio na Pra\u00e7a Conselheiro Macedo Soares (Pra\u00e7a do Turismo), no Centro. T\u00e9cnicos dos Centros de Aten\u00e7\u00e3o Psicossocial (Caps) realizaram o acolhimento daqueles que passam por momentos dif\u00edceis, al\u00e9m de esclarecerem d\u00favidas da popula\u00e7\u00e3o e apresentarem os servi\u00e7os gratuitos de sa\u00fade mental existentes na cidade. A atividade ocorre at\u00e9 a sexta-feira (24), das 9h \u00e0s 13h, integrando a campanha nacional do Setembro Amarelo, m\u00eas de valoriza\u00e7\u00e3o da vida.<\/p>\n\n\n\n<p>\u201c\u00c9 importante estar na rua para conversar com a popula\u00e7\u00e3o, pois \u00e9 um tema delicado e nem todos sabem como procurar ajuda. \u00c0s vezes, aqueles que abordamos n\u00e3o passam por esses problemas, mas conhecem algu\u00e9m que precisa de aux\u00edlio, ent\u00e3o passamos os endere\u00e7os dos Caps, dos postos pr\u00f3ximos \u00e0s resid\u00eancias e outras informa\u00e7\u00f5es que podem fazer a diferen\u00e7a\u201d, explicou a gerente do Caps II, Val\u00e9ria Cristina de Azevedo. \u201cJ\u00e1 estamos fazendo o acolhimento dos que mais precisam. As Unidades de Sa\u00fade da Fam\u00edlia (USF) est\u00e3o realizando esses trabalhos nos bairros, nas salas de espera e com a elabora\u00e7\u00e3o de rodas de conversa\u201d, completou.<\/p>\n\n\n\n<p><strong>Popula\u00e7\u00e3o valoriza o acolhimento<\/strong><\/p>\n\n\n\n<p>As pessoas que passavam pela regi\u00e3o central da cidade nesta segunda-feira (20) mostraram satisfa\u00e7\u00e3o com o suporte \u00e0 sa\u00fade mental oferecido pela equipe. Para a aut\u00f4noma Cl\u00e1udia Oliveira, de 46 anos, os servi\u00e7os de sa\u00fade existentes na cidade fazem a diferen\u00e7a na realidade dos mais vulner\u00e1veis.<\/p>\n\n\n\n<p>\u201c\u00c9 muito importante ter um trabalho como esse em Maric\u00e1. Muitas pessoas n\u00e3o conhecem os servi\u00e7os em sa\u00fade mental que a cidade oferece e, com essa abordagem, conseguem orienta\u00e7\u00f5es relevantes. Alguns moradores sofrem e n\u00e3o t\u00eam a quem recorrer, faltando inclusive o suporte familiar. Os Caps s\u00e3o ferramentas para promover esse apoio, principalmente com a pandemia da Covid-19, que fragilizou muita gente\u201d, pontuou.<\/p>\n\n\n\n<p>A auxiliar de loja Josete Aparecida, de 42 anos, destacou a relev\u00e2ncia do suporte, principalmente aos jovens, que muitas vezes possuem maior dificuldade em compartilhar os dilemas que enfrentam.<\/p>\n\n\n\n<p>\u201cGostei muito de toda a aten\u00e7\u00e3o e orienta\u00e7\u00e3o das t\u00e9cnicas da sa\u00fade. A Prefeitura est\u00e1 fazendo um \u00f3timo trabalho e \u00e9 muito importante olharmos com aten\u00e7\u00e3o os que passam por problemas relacionados \u00e0 sa\u00fade mental, em especial aos jovens. A fam\u00edlia, por vezes, n\u00e3o tem estrutura para lidar com essas quest\u00f5es e h\u00e1 certa resist\u00eancia em compartilhar os problemas, ent\u00e3o essa ajuda profissional \u00e9 essencial\u201d, ressaltou.<\/p>\n\n\n\n<p><strong>Busca ativa e a\u00e7\u00f5es integradas<\/strong><\/p>\n\n\n\n<p>Al\u00e9m da atividade de acolhimento na Pra\u00e7a do Turismo, equipes do projeto atuam tamb\u00e9m na regi\u00e3o comercial do entorno e no Terminal Rodovi\u00e1rio do Centro. Atrav\u00e9s dessa a\u00e7\u00e3o, \u00e9 feita uma busca ativa aos que possam estar enfrentando problemas mentais ou conhe\u00e7am pessoas que necessitem de assist\u00eancia.<\/p>\n\n\n\n<p>A partir desta ter\u00e7a-feira (21), a tenda montada na pra\u00e7a contar\u00e1 tamb\u00e9m com medi\u00e7\u00e3o de press\u00e3o e uma oficina voltada ao corpo e a mente, trabalhando de forma interligada a sa\u00fade mental.<\/p>\n\n\n\n<p><strong>Saiba como ajudar<\/strong><\/p>\n\n\n\n<p>Nos casos de tentativa de suic\u00eddio, os familiares t\u00eam \u00e0 disposi\u00e7\u00e3o os servi\u00e7os de urg\u00eancia e emerg\u00eancia \u2013 Hospital Municipal Conde Modesto Leal, no Centro, Unidade de Pronto Atendimento (UPA) de Ino\u00e3, Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) \u2013 para realiza\u00e7\u00e3o dos primeiros socorros e avalia\u00e7\u00e3o do quadro cl\u00ednico geral.<\/p>\n\n\n\n<p>Depois, os Centros de Aten\u00e7\u00e3o Psicossocial (Caps) ser\u00e3o notificados pela necessidade do cuidado mais intensivo ap\u00f3s o ato. Os Caps s\u00e3o suporte tanto para as tentativas de suic\u00eddio, como para as demais viol\u00eancias autopraticadas. A Secretaria de Sa\u00fade ressalta que \u00e9 fundamental o familiar ou o pr\u00f3prio paciente pedir ajuda nos Caps ou em uma das 24 Unidades de Sa\u00fade da Fam\u00edlia de Maric\u00e1. Em Maric\u00e1, existem ainda o CAPS Infanto-Juvenil (Capsi) e de \u00c1lcool e Drogas (Caps AD).<\/p>\n\n\n\n<p><strong>Veja onde procurar ajuda<\/strong><\/p>\n\n\n\n<p>Centro de Aten\u00e7\u00e3o Psicossocial (CAPS) \u2013 Rua Cl\u00edmaco Pereira n\u00ba 259 \u2013 Centro \u2013 Telefone:&nbsp;<a href=\"tel:(21) 2637-2578\">(21) 2637-2578<\/a><\/p>\n\n\n\n<p>Centro de Aten\u00e7\u00e3o Psicossocial Infanto Juvenil (CAPSI) \u2013 Rua Eug\u00eania Modesto da Silva n\u00ba 363 \u2013 Parque Eldorado \u2013 Telefone:&nbsp;<a href=\"tel:(21) 2637-3941\">(21) 2637-3941<\/a>&nbsp;ou&nbsp;<a href=\"tel:(21) 97045-1244\">(21) 97045-1244<\/a><\/p>\n\n\n\n<p>Centro de Aten\u00e7\u00e3o Psicossocial \u00c1lcool e Drogas (CAPS AD) \u2013 Rua Eug\u00eania Modesto da Silva, n\u00ba 107 \u2013 lote 03, Quadra K \u2013 Loteamento Parque Eldorado \u2013 Centro \u2013 Telefone:&nbsp;<a href=\"tel:(21) 2637-6830\">(21) 2637-6830<\/a>&nbsp;ou&nbsp;<a href=\"tel:(21) 96484-7695\">(21) 96484-7695<\/a>.<\/p>\n\n\n\n<p>Centro de Valoriza\u00e7\u00e3o da Vida (CVV) \u2013 Suporte emocional e preventivo gratuito, 24 horas \u2013 Telefone: 188.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria Municipal de Sa\u00fade, promoveu nesta segunda-feira (20\/09) o primeiro dia da A\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":28938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-28937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=28937"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28937\/revisions"}],"predecessor-version":[{"id":28939,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28937\/revisions\/28939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/28938"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=28937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=28937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=28937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}