{"id":28979,"date":"2021-09-22T07:14:23","date_gmt":"2021-09-22T10:14:23","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=28979"},"modified":"2021-09-22T07:14:25","modified_gmt":"2021-09-22T10:14:25","slug":"reformada-upa-inoa-celebra-9-anos-de-atendimentos-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/09\/22\/reformada-upa-inoa-celebra-9-anos-de-atendimentos-em-marica\/","title":{"rendered":"Reformada, UPA Ino\u00e3 celebra 9 anos de atendimentos em Maric\u00e1"},"content":{"rendered":"\n<p>A Unidade de Pronto Atendimento (UPA) de Ino\u00e3, em Maric\u00e1, completou 9 anos de funcionamento neste domingo (19). Al\u00e9m do atendimento de qualidade ofertado \u00e0 popula\u00e7\u00e3o (quase 70 mil nos \u00faltimos 11 meses), a unidade de sa\u00fade celebrou o t\u00e9rmino das obras de revitaliza\u00e7\u00e3o do espa\u00e7o, que tem 1.638 m\u00b2 de \u00e1rea constru\u00edda.<\/p>\n\n\n\n<p>O prefeito Fabiano Horta visitou a unidade nesta segunda-feira (20) e lembrou da dificuldade para a implanta\u00e7\u00e3o dessa unidade e refor\u00e7ou o compromisso com a sa\u00fade da popula\u00e7\u00e3o de Maric\u00e1.<\/p>\n\n\n\n<p>\u201cEu me lembro da luta para que a gente pudesse conquistar essa unidade, para que ela pudesse ser aberta em Maric\u00e1. Estamos aqui hoje celebrando e inaugurando uma reforma bela e funcional, por\u00e9m, mais do que isso, exaltamos o fato da UPA fazer parte do nosso conjunto de aparelhos da Sa\u00fade, que defende e protege os nossos cidad\u00e3os e os de fora. Seguimos comprometidos em continuar construindo um SUS cada vez mais forte\u201d destacou o prefeito.<\/p>\n\n\n\n<p>A UPA passou por servi\u00e7os de troca de piso vin\u00edlico, reformula\u00e7\u00e3o de toda recep\u00e7\u00e3o com novo mobili\u00e1rio e ilha de atendimento ao usu\u00e1rio. Al\u00e9m de novo mobili\u00e1rio na maioria das salas, foram instalados novos leitos na sala vermelha, e foi feito o redimensionamento e revitaliza\u00e7\u00e3o de todo sistema de refrigera\u00e7\u00e3o e ilumina\u00e7\u00e3o da Unidade. As crian\u00e7as tamb\u00e9m receberam um espa\u00e7o de intera\u00e7\u00e3o mais humanizado para o ambiente hospitalar se tornar mais leve e menos ocioso.<\/p>\n\n\n\n<p>\u201cAs obras visam a melhoria da infraestrutura para melhorar o acolhimento aos pacientes que nos procuram. O objetivo sempre foi o protagonismo da qualidade na assist\u00eancia em sa\u00fade, oferecida gratuitamente, atrav\u00e9s do SUS\u201d, destacou a diretora m\u00e9dica da UPA, Juliana Nogueira.<\/p>\n\n\n\n<p>A secret\u00e1ria municipal de Sa\u00fade, Solange Oliveira, destacou a preocupa\u00e7\u00e3o da pasta com os detalhes para um atendimento cada vez mais humanizado.<\/p>\n\n\n\n<p>\u201c\u00c9 muito gratificante olhar esse espa\u00e7o e ver que o carinho de cada um que aqui trabalha. N\u00e3o s\u00f3 na estrutura, mas no cuidado \u00e0s pessoas. Quantas delas aqui foram cuidadas e salvas. Quantas vidas passaram por aqui e ganharam novo sentido nesse espa\u00e7o\u201d, enalteceu a secret\u00e1ria.<\/p>\n\n\n\n<p>J\u00e1 o subsecret\u00e1rio da Rede de Urg\u00eancia e Emerg\u00eancia, Glauco Pontes, destacou a UPA Ino\u00e3 como um equipamento fundamental para a Sa\u00fade de Maric\u00e1.<\/p>\n\n\n\n<p>\u201cEstou no munic\u00edpio h\u00e1 quase 16 anos na \u00e1rea m\u00e9dica e n\u00e3o consigo lembrar como era o munic\u00edpio sem a UPA de t\u00e3o importante que ela se tornou. A unidade faz uma integra\u00e7\u00e3o excelente com Posto 24 horas Santa Rita e ao Conde, e ainda consegue acolher um trecho populacional muito grande, sendo uma pe\u00e7a indispens\u00e1vel nessa rede\u201d, concluiu.<\/p>\n\n\n\n<p><strong>Homenagem<\/strong><\/p>\n\n\n\n<p>Nesta segunda-feira (20) a dire\u00e7\u00e3o da UPA prestou homenagem \u00e0 primeira profissional de sa\u00fade do munic\u00edpio v\u00edtima da Covid-19, Denise Gomes. Ela foi t\u00e9cnica de enfermagem e faleceu em abril de 2020. A Sala Vermelha da UPA, a partir de agora, carregar\u00e1 seu nome. Foram homenageadas tamb\u00e9m duas outras colaboradoras internadas na mesma \u00e9poca que Denise, mas que se recuperaram: a enfermeira Elaine Rangel e a supervisora administrativa Ana Paula de Souza.<\/p>\n\n\n\n<p>A m\u00e3e de Denise, Araci Gomes, esteve presente durante a homenagem e se emocionou.<\/p>\n\n\n\n<p>\u201cMinha filha falava com muito carinho da UPA. Dizia que esse lugar era a vida e a casa dela. N\u00e3o \u00e9 porque \u00e9 minha filha, mas era muito dedicada. Ela amava a sa\u00fade e ajudava as pessoas\u201d, declarou.<\/p>\n\n\n\n<p><strong>Atendimento Covid<\/strong><\/p>\n\n\n\n<p>A Unidade de Pronto Atendimento (UPA) de Ino\u00e3 tamb\u00e9m tria pacientes com sintomas da Covid-19 no munic\u00edpio, em tenda separada em sua \u00e1rea externa. A unidade de sa\u00fade possui 20 leitos para a observa\u00e7\u00e3o de pacientes, cinco deles s\u00e3o destinados ao acolhimento do coronav\u00edrus at\u00e9 a transfer\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Unidade de Pronto Atendimento (UPA) de Ino\u00e3, em Maric\u00e1, completou 9 anos de funcionamento neste domingo (19). Al\u00e9m do<\/p>\n","protected":false},"author":1,"featured_media":28980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-28979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=28979"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28979\/revisions"}],"predecessor-version":[{"id":28981,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/28979\/revisions\/28981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/28980"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=28979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=28979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=28979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}