{"id":29116,"date":"2021-09-24T13:23:05","date_gmt":"2021-09-24T16:23:05","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=29116"},"modified":"2021-09-24T13:23:06","modified_gmt":"2021-09-24T16:23:06","slug":"prefeitura-promove-evento-sobre-sensibilizacao-da-surdez","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/09\/24\/prefeitura-promove-evento-sobre-sensibilizacao-da-surdez\/","title":{"rendered":"Prefeitura promove evento sobre sensibiliza\u00e7\u00e3o da surdez"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Pol\u00edticas Inclusivas, realiza nesta sexta-feira (24\/9) o evento \u2018Sensibiliza\u00e7\u00e3o sobre a Surdez\u2019, que tem o objetivo de mostrar uma nova consci\u00eancia sobre pessoas com diferentes n\u00edveis de baixa audi\u00e7\u00e3o. Est\u00e3o programadas din\u00e2micas, apresenta\u00e7\u00e3o de dan\u00e7a e palestras com o motorista de aplicativo Romildo Ladeira J\u00fanior e com a pedagoga Gilvana Amorim Pinna, ambos surdos. O evento, aberto ao p\u00fablico, ocorre das 9h \u00e0s 12h no Centro de Refer\u00eancia de Pol\u00edticas Inclusivas, que fica na Rua Boaz Velasco, no Centro.<\/p>\n\n\n\n<p>Uma das organizadoras da a\u00e7\u00e3o, Karen Bill\u00e9, explicou que a ideia \u00e9 gerar no p\u00fablico um tipo de impacto mais amplo, que vai al\u00e9m da conscientiza\u00e7\u00e3o. \u201cO que queremos \u00e9 criar empatia. As palestras v\u00e3o falar sobre mercado de trabalho e dificuldades de coloca\u00e7\u00e3o, entre outros itens\u201d, adiantou a int\u00e9rprete da Linguagem Brasileira de Sinais (Libras), ao observar que h\u00e1 uma s\u00e9rie de especificidades que essas pessoas t\u00eam e que muita gente desconhece.<\/p>\n\n\n\n<p>\u201cEles preferem ser chamados de surdos mesmo. \u00c9 melhor at\u00e9 do que pessoas com defici\u00eancia auditiva, mas nunca chame um deles de \u2018surdinho\u2019, o que \u00e9 considerado depreciativo. Alguns s\u00e3o inclusive contra o uso de aparelhos para aumentar a audi\u00e7\u00e3o, como o implante coclear. \u00c9 algo que tem a ver com aceitar essa condi\u00e7\u00e3o de surdo e, dentro dessa ideia, os n\u00e3o-surdos \u00e9 que devem procurar se comunicar com eles e n\u00e3o o contr\u00e1rio\u201d, esclareceu Karen.<\/p>\n\n\n\n<p>A secret\u00e1ria de Pol\u00edticas Inclusivas, Sheila Pinto, ressaltou que um dos objetivos do evento \u2013 na data que se comemora o Dia Internacional da Linguagem de Sinais \u2013 \u00e9 o de estimular a intera\u00e7\u00e3o entre a sociedade e as pessoas surdas. \u201c\u00c9 preciso fazer com que as pessoas interajam. \u00c9 preciso que a sociedade sabia da exist\u00eancia dessas pessoas com surdez, e que se integrem\u201d, frisou ela.<\/p>\n\n\n\n<p>Durante o evento, tamb\u00e9m ser\u00e1 anunciado o passeio guiado para Pessoa com Defici\u00eancia Auditiva e acompanhantes ao Museu do Amanh\u00e3, no Centro do Rio, em fun\u00e7\u00e3o da comemora\u00e7\u00e3o ao Setembro Azul, m\u00eas dedicado aos surdos. O traslado ser\u00e1 feito gratuitamente junto com o passaporte de entrada. O passeio contar\u00e1 com a presen\u00e7a de int\u00e9rpretes de LIBRAS e est\u00e1 marcado para a pr\u00f3xima sexta-feira (01\/10), saindo \u00e0s 8h30 do Centro de Refer\u00eancia e retornando \u00e0s 15h30.<\/p>\n\n\n\n<p>Quem quiser participar pode se inscrever no decorrer do evento ou at\u00e9 segunda-feira (27\/9) de forma presencial, pelo site www.maricapoliticasinclusivas.com.br ou pelo telefone&nbsp;<a href=\"tel:3005-4107\">3005-4107<\/a>. Os interessados devem ter a partir de 14 anos e ter recebido as duas doses da vacina\u00e7\u00e3o contra Covid-19, sendo necess\u00e1ria apresenta\u00e7\u00e3o do cart\u00e3o de vacina\u00e7\u00e3o. O uso de m\u00e1scara \u00e9 obrigat\u00f3rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Pol\u00edticas Inclusivas, realiza nesta sexta-feira (24\/9) o evento \u2018Sensibiliza\u00e7\u00e3o sobre a<\/p>\n","protected":false},"author":1,"featured_media":29117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-29116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=29116"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29116\/revisions"}],"predecessor-version":[{"id":29118,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29116\/revisions\/29118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/29117"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=29116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=29116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=29116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}