{"id":29643,"date":"2021-10-13T18:32:29","date_gmt":"2021-10-13T21:32:29","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=29643"},"modified":"2021-10-13T18:32:30","modified_gmt":"2021-10-13T21:32:30","slug":"senhor-cai-de-van-apos-descer-bate-com-a-cabeca-no-chao-e-fica-gravemente-ferido-no-centro-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/10\/13\/senhor-cai-de-van-apos-descer-bate-com-a-cabeca-no-chao-e-fica-gravemente-ferido-no-centro-de-marica\/","title":{"rendered":"Senhor cai de van ap\u00f3s descer, bate com a cabe\u00e7a no ch\u00e3o e fica gravemente ferido no Centro de Maric\u00e1"},"content":{"rendered":"\n<p>Um senhor ficou gravemente ferido ap\u00f3s descer de uma van e cair, em frente ao Hospital Municipal Conde Modesto Leal, no Centro de Maric\u00e1, na tarde desta quarta-feira (13).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o senhor foi descer da van, se desequilibrou e caiu, batendo com a cabe\u00e7a no ch\u00e3o.<\/p>\n\n\n\n<p>Socorristas do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) seguiram rapidamente para o local e prestaram os primeiros socorros para a v\u00edtima. Em seguida, homem foi encaminhado para a unidade hospitalar.<\/p>\n\n\n\n<p>O estado de sa\u00fade e a identidade do senhor n\u00e3o foram revelados.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um senhor ficou gravemente ferido ap\u00f3s descer de uma van e cair, em frente ao Hospital Municipal Conde Modesto Leal,<\/p>\n","protected":false},"author":1,"featured_media":29644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-29643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=29643"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29643\/revisions"}],"predecessor-version":[{"id":29645,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/29643\/revisions\/29645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/29644"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=29643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=29643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=29643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}