{"id":30391,"date":"2021-11-07T14:48:03","date_gmt":"2021-11-07T17:48:03","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=30391"},"modified":"2021-11-07T14:48:04","modified_gmt":"2021-11-07T17:48:04","slug":"prefeitura-de-marica-atualiza-bilhete-unico-universitario","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/11\/07\/prefeitura-de-marica-atualiza-bilhete-unico-universitario\/","title":{"rendered":"Prefeitura de Maric\u00e1 atualiza Bilhete \u00danico Universit\u00e1rio"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1 realizou neste s\u00e1bado (06\/11) o \u00faltimo dia de recadastramento dos estudantes beneficiados pelo programa Bilhete \u00danico Universit\u00e1rio.<\/p>\n\n\n\n<p>De acordo com a Secretaria de Assist\u00eancia Social, cerca de 2.100 alunos fizeram a devida atualiza\u00e7\u00e3o em um dos quatro polos presentes na cidade, procedimento essencial para comprovar a necessidade do benef\u00edcio, ap\u00f3s um longo per\u00edodo sem aulas presenciais nas universidades.<\/p>\n\n\n\n<p>Para Jorge Castor, secret\u00e1rio de Assist\u00eancia Social, o saldo de recadastramento foi positivo.<\/p>\n\n\n\n<p>\u201cMuitos alunos j\u00e1 se formaram, j\u00e1 mudaram de cidade ou simplesmente a universidade ainda n\u00e3o voltou com atividades presenciais, o que torna esse saldo de mais de dois mil estudantes recadastrados muito positivo\u201d, avaliou o secret\u00e1rio. \u201cAgora vamos verificar os estudantes que por algum motivo n\u00e3o conseguiram fazer a atualiza\u00e7\u00e3o e vamos resolver caso a caso\u201d, garantiu Castor.<\/p>\n\n\n\n<p><strong>Novos cadastros<\/strong><\/p>\n\n\n\n<p>O secret\u00e1rio afirmou que a expectativa agora \u00e9 para os estudantes que ir\u00e3o solicitar o benef\u00edcio pela primeira vez.<\/p>\n\n\n\n<p>\u201cEm breve, ainda em novembro, vamos divulgar as datas para os estudantes que desejam fazer parte do programa e obter o seu Bilhete \u00danico Universit\u00e1rio\u201d, disse.<\/p>\n\n\n\n<p>A estudante M\u00e1rcia Cristina, de 23 anos, moradora de Cordeirinho, elogiou o atendimento prestado pela equipe de recadastramento presente no CEM Joana Benedicta Rangeu, no Centro.<\/p>\n\n\n\n<p>\u201cFoi tudo muito r\u00e1pido, as pessoas aqui s\u00e3o muito prestativas e me tiraram todas as d\u00favidas\u201d, afirmou M\u00e1rcia. \u201cEsse benef\u00edcio \u00e9 excelente, pois \u00e9 uma ajuda de custo muito grande para n\u00f3s universit\u00e1rios e, o recadastramento \u00e9 uma forma de saber se est\u00e1 tudo certo e de atualizar as informa\u00e7\u00f5es de cada estudante do munic\u00edpio\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1 realizou neste s\u00e1bado (06\/11) o \u00faltimo dia de recadastramento dos estudantes beneficiados pelo programa Bilhete \u00danico<\/p>\n","protected":false},"author":1,"featured_media":30392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-30391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=30391"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30391\/revisions"}],"predecessor-version":[{"id":30393,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30391\/revisions\/30393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/30392"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=30391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=30391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=30391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}