{"id":30431,"date":"2021-11-09T10:57:24","date_gmt":"2021-11-09T13:57:24","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=30431"},"modified":"2021-11-09T10:57:26","modified_gmt":"2021-11-09T13:57:26","slug":"marica-processo-seletivo-da-saude-tem-gabarito-divulgado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/11\/09\/marica-processo-seletivo-da-saude-tem-gabarito-divulgado\/","title":{"rendered":"Maric\u00e1: Processo seletivo da Sa\u00fade tem gabarito divulgado"},"content":{"rendered":"\n<p>O gabarito do processo seletivo da \u00e1rea de Sa\u00fade de Maric\u00e1, realizado no \u00faltimo s\u00e1bado, teve o gabarito divulgado nesta segunda-feira (08) pela Associa\u00e7\u00e3o Mahatma Ghandi.<\/p>\n\n\n\n<p>Com vagas disponibilizadas para o Posto Santa Rita, em Itaipua\u00e7u, Unidade de Pronto Atendimento (UPA), em Ino\u00e3, e no Hospital Municipal Conde Modesto Leal, no Centro, a a\u00e7\u00e3o tem a finalidade de encorpar uma das \u00e1reas mais importantes da cidade.<\/p>\n\n\n\n<p>Confira o gabarito:<\/p>\n\n\n\n<p><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/B3EF3C17-BF6D-4D96-8ED1-E39A2BD891FB-748x1024.jpeg\" alt=\"\" class=\"wp-image-30432\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/B3EF3C17-BF6D-4D96-8ED1-E39A2BD891FB-748x1024.jpeg 748w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/B3EF3C17-BF6D-4D96-8ED1-E39A2BD891FB-219x300.jpeg 219w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/B3EF3C17-BF6D-4D96-8ED1-E39A2BD891FB.jpeg 750w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/59E0BAA1-E345-4E66-98A2-B25733511FBD-732x1024.jpeg\" alt=\"\" class=\"wp-image-30433\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/59E0BAA1-E345-4E66-98A2-B25733511FBD-732x1024.jpeg 732w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/59E0BAA1-E345-4E66-98A2-B25733511FBD-214x300.jpeg 214w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/59E0BAA1-E345-4E66-98A2-B25733511FBD.jpeg 750w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"731\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/7BA1B2C6-87BE-4A44-94CD-1739B495CA64-731x1024.jpeg\" alt=\"\" class=\"wp-image-30434\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/7BA1B2C6-87BE-4A44-94CD-1739B495CA64-731x1024.jpeg 731w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/7BA1B2C6-87BE-4A44-94CD-1739B495CA64-214x300.jpeg 214w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/7BA1B2C6-87BE-4A44-94CD-1739B495CA64.jpeg 750w\" sizes=\"auto, (max-width: 731px) 100vw, 731px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/FE3758CD-3FA2-4879-8DB7-4F85633A75F5-737x1024.jpeg\" alt=\"\" class=\"wp-image-30435\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/FE3758CD-3FA2-4879-8DB7-4F85633A75F5-737x1024.jpeg 737w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/FE3758CD-3FA2-4879-8DB7-4F85633A75F5-216x300.jpeg 216w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/FE3758CD-3FA2-4879-8DB7-4F85633A75F5.jpeg 750w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5B9A18A6-4B67-4C7D-95A1-95CC0E74D81F-740x1024.jpeg\" alt=\"\" class=\"wp-image-30436\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5B9A18A6-4B67-4C7D-95A1-95CC0E74D81F-740x1024.jpeg 740w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5B9A18A6-4B67-4C7D-95A1-95CC0E74D81F-217x300.jpeg 217w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5B9A18A6-4B67-4C7D-95A1-95CC0E74D81F.jpeg 750w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/DC812F76-E856-4381-A3DB-BC8520A88734-729x1024.jpeg\" alt=\"\" class=\"wp-image-30437\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/DC812F76-E856-4381-A3DB-BC8520A88734-729x1024.jpeg 729w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/DC812F76-E856-4381-A3DB-BC8520A88734-214x300.jpeg 214w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/DC812F76-E856-4381-A3DB-BC8520A88734.jpeg 750w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"743\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/0C01084A-558B-40E1-BDC9-82C5FD2BAC41-743x1024.jpeg\" alt=\"\" class=\"wp-image-30438\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/0C01084A-558B-40E1-BDC9-82C5FD2BAC41-743x1024.jpeg 743w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/0C01084A-558B-40E1-BDC9-82C5FD2BAC41-218x300.jpeg 218w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/0C01084A-558B-40E1-BDC9-82C5FD2BAC41.jpeg 750w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"1024\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5F3A3B35-090C-4AC4-95F0-6D95E99F11CC-728x1024.jpeg\" alt=\"\" class=\"wp-image-30439\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5F3A3B35-090C-4AC4-95F0-6D95E99F11CC-728x1024.jpeg 728w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5F3A3B35-090C-4AC4-95F0-6D95E99F11CC-213x300.jpeg 213w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2021\/11\/5F3A3B35-090C-4AC4-95F0-6D95E99F11CC.jpeg 750w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O gabarito do processo seletivo da \u00e1rea de Sa\u00fade de Maric\u00e1, realizado no \u00faltimo s\u00e1bado, teve o gabarito divulgado nesta<\/p>\n","protected":false},"author":1,"featured_media":30440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-30431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=30431"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30431\/revisions"}],"predecessor-version":[{"id":30441,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30431\/revisions\/30441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/30440"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=30431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=30431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=30431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}