{"id":30447,"date":"2021-11-09T11:41:50","date_gmt":"2021-11-09T14:41:50","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=30447"},"modified":"2021-11-09T11:41:51","modified_gmt":"2021-11-09T14:41:51","slug":"mprj-e-defensoria-peticionam-ao-stj-para-que-seja-interrompido-projeto-maraey-na-area-de-protecao-ambiental-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/11\/09\/mprj-e-defensoria-peticionam-ao-stj-para-que-seja-interrompido-projeto-maraey-na-area-de-protecao-ambiental-de-marica\/","title":{"rendered":"MPRJ e Defensoria peticionam ao STJ para que seja interrompido projeto MARAEY na \u00c1rea de Prote\u00e7\u00e3o Ambiental de Maric\u00e1"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico do Estado do Rio de Janeiro (MPRJ), por meio da Assessoria de Recursos Constitucionais C\u00edveis, e a Associa\u00e7\u00e3o Comunit\u00e1ria de Cultura e Lazer dos Pescadores Zacarias (ACCAPLEZ), representada pela Defensoria P\u00fablica do Rio, peticionaram, no dia 29\/10,&nbsp; ao Ministro Herman Benjamin, do STJ,&nbsp; solicitando a publica\u00e7\u00e3o de&nbsp;decis\u00e3o proferida em abril que mant\u00e9m os efeitos do Ac\u00f3rd\u00e3o prolatado no Agravo de Instrumento n. 0028812-96.2013.8.19.0000, que determinou a suspens\u00e3o de todos os pedidos de licenciamento, loteamento, constru\u00e7\u00e3o ou instala\u00e7\u00e3o de qualquer empreendimento no interior e entorno da APA de Maric\u00e1.<\/p>\n\n\n\n<p>A peti\u00e7\u00e3o foi motivada pelo fato de que, valendo-se dessa pend\u00eancia na publica\u00e7\u00e3o, o Conselho Diretor do Instituto Estadual do Ambiente (CONDIR\/INEA), em 6\/10, aprovou a licen\u00e7a de instala\u00e7\u00e3o das obras do empreendimento imobili\u00e1rio privado Maraey. Para festejar a entrega da licen\u00e7a foi realizado, em 28\/10, evento p\u00fablico de ampla divulga\u00e7\u00e3o nas m\u00eddias sociais. O lan\u00e7amento do empreendimento&nbsp; contou com a presen\u00e7a de diversas autoridades p\u00fablicas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u201cNeste contexto, em que o formalismo est\u00e1 servindo de brecha para a afronta a decis\u00e3o judicial e o pior, \u00e9 celebrado por diversas autoridades p\u00fablicas, entendemos ser necess\u00e1rio relembrar aos interessados que a constru\u00e7\u00e3o do Resort n\u00e3o foi autorizada e, portanto, qualquer ato tendente ao licenciamento e execu\u00e7\u00e3o de obras importar\u00e1 em afronta \u00e0 autoridade do Poder Judici\u00e1rio\u201d, diz a peti\u00e7\u00e3o.<\/p>\n\n\n\n<p>O documento requer a expedi\u00e7\u00e3o de of\u00edcio ao Presidente do Instituto Estadual do Ambiente (INEA), ao Prefeito do Munic\u00edpio de Maric\u00e1 e \u00e0 Procuradoria Geral do Estado do Rio de Janeiro para que, a fim de preservar a lisura de seus atos, se abstenham de prosseguir no processo de licenciamento, loteamento, constru\u00e7\u00e3o ou instala\u00e7\u00e3o de qualquer empreendimento no interior e entorno da APA (\u00e1rea de Prote\u00e7\u00e3o Ambiental) de Maric\u00e1, sob pena do crime de desobedi\u00eancia previsto no artigo 330 do C\u00f3digo Penal.<\/p>\n\n\n\n<p>O ac\u00f3rd\u00e3o do STJ j\u00e1 tem aptid\u00e3o para impedir todos os pedidos de licenciamento o empreendimento. No entanto, al\u00e9m da pend\u00eancia na publica\u00e7\u00e3o desse ac\u00f3rd\u00e3o, os empreendedores tamb\u00e9m se basearam em ac\u00f3rd\u00e3o da 18\u00aa C\u00e2mara C\u00edvel, que, no dia 07\/10, anulou a decis\u00e3o de 1\u00ba grau na ACP de origem para dar continuidade ao projeto. Com rela\u00e7\u00e3o a essa decis\u00e3o do Tribunal de Justi\u00e7a do Rio (TJRJ), o MPRJ analisa a possibilidade de interposi\u00e7\u00e3o de Recurso para as Cortes Superiores.<\/p>\n\n\n\n<p>Sem que tivesse ci\u00eancia da decis\u00e3o do INEA, j\u00e1 que n\u00e3o informada nos autos da A\u00e7\u00e3o Civil P\u00fablica, nem diretamente ao Minist\u00e9rio P\u00fablico, em 28\/10, a Promotoria de Justi\u00e7a de Tutela Coletiva de Defesa do Meio Ambiente do N\u00facleo Niter\u00f3i reuniu-se, na parte da tarde, com o reprentantes do instituto para verificar a proced\u00eancia da not\u00edcia de emiss\u00e3o da licen\u00e7a de instala\u00e7\u00e3o, o que foi confirmado. Al\u00e9m disso, em 05\/11, o MPRJ esteve, em conjunto com a Presid\u00eancia do INEA e a Defensoria P\u00fablica, em dilig\u00eancia in loco a fim de apurar dados relacionados \u00e0 licen\u00e7a emitida, o que permitir\u00e1 nova an\u00e1lise pelo Grupo de Apoio T\u00e9cnico Especializado (GATE\/MPRJ).<\/p>\n\n\n\n<p>Na oportunidade, houve a apresenta\u00e7\u00e3o, pelo INEA, do projeto que foi licenciado, tendo o \u00f3rg\u00e3o ambiental mencionado a implanta\u00e7\u00e3o de uma RPPN \u2013 Reserva Particular do Patrim\u00f4nio Natural e que, devido ao porte do empreendimento haver\u00e1 o faseamento do licenciamento, com a expedi\u00e7\u00e3o de Licen\u00e7a de Instala\u00e7\u00e3o apenas para a execu\u00e7\u00e3o de obras de infraestrutura, inclusive vi\u00e1ria. Estiveram presentes tamb\u00e9m \u00e0 apresenta\u00e7\u00e3o uma representante da APALMA (Associa\u00e7\u00e3o de Preserva\u00e7\u00e3o Ambiental das Lagunas de Maric\u00e1) e uma representante da comunidade acad\u00eamica que estuda os impactos ambientais desse empreendimento \u00e0 APA de Maric\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico do Estado do Rio de Janeiro (MPRJ), por meio da Assessoria de Recursos Constitucionais C\u00edveis, e a<\/p>\n","protected":false},"author":1,"featured_media":30443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-30447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=30447"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30447\/revisions"}],"predecessor-version":[{"id":30448,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30447\/revisions\/30448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/30443"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=30447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=30447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=30447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}