{"id":30682,"date":"2021-11-19T07:38:48","date_gmt":"2021-11-19T10:38:48","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=30682"},"modified":"2021-11-19T07:38:49","modified_gmt":"2021-11-19T10:38:49","slug":"prefeitura-realiza-projeto-ao-lado-do-idolo-com-alunos-do-marica-esporte-2","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/11\/19\/prefeitura-realiza-projeto-ao-lado-do-idolo-com-alunos-do-marica-esporte-2\/","title":{"rendered":"Prefeitura realiza projeto \u201cAo lado do \u00cddolo\u201d com alunos do Maric\u00e1 + Esporte 2"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1 realizou nesta quinta-feira (18\/11) a Cl\u00ednica de Atletismo e Futebol no Parque a C\u00e9u Aberto do Parque Nanci. A atividade promovida pela Secretaria de Esporte e Lazer teve a participa\u00e7\u00e3o de 50 alunos do Projeto Maric\u00e1 +Esporte 2 e contou com a presen\u00e7a do convidado especial o preparador f\u00edsico Carlos Alberto Lancetta.<\/p>\n\n\n\n<p>O convidado foi t\u00e9cnico da sele\u00e7\u00e3o brasileira de Atletismo na Olimp\u00edada de Montreal, em 1976, e preparador f\u00edsico dos quatro principais clubes de futebol do Rio de Janeiro e tamb\u00e9m em S\u00e3o Paulo.<\/p>\n\n\n\n<p>O projeto \u201cAo Lado do \u00cddolo\u201d tem como objetivo integrar alunos das modalidades esportivas oferecidas pelo Maric\u00e1+Esporte 2 com os principais \u00eddolos esportivos.<\/p>\n\n\n\n<p>O secret\u00e1rio de Esporte e Lazer, Filipe Bittencourt, destaca que nesses encontros s\u00e3o compartilhadas experi\u00eancias profissionais e valores essenciais dos esportistas, servindo de refer\u00eancia aos praticantes de Maric\u00e1.<\/p>\n\n\n\n<p>\u201cA iniciativa \u00e9 uma oportunidade para os alunos aprenderem com grandes nomes do esporte, a partir da experi\u00eancia desses profissionais\u201d, disse.<\/p>\n\n\n\n<p>O preparador f\u00edsico, Carlos Alberto Lancetta, comentou a experi\u00eancia de poder partilhar sua viv\u00eancia.<br>\u201c\u00c9 muito bom ver esse projeto em Maric\u00e1, uma cidade em ascens\u00e3o e que investe nos esportes. Ver essas crian\u00e7as tendo a oportunidade de entrar no meio esportivo \u00e9 uma satisfa\u00e7\u00e3o e, futuramente, grandes atletas poder\u00e3o surgir aqui\u201d, pontuou.<\/p>\n\n\n\n<p><strong>Alunos apoiam o projeto \u201cAo Lado do \u00cddolo\u201d<\/strong><\/p>\n\n\n\n<p>Os participantes do projeto se mostraram animados com a troca de conhecimentos. O aluno Lucas Hilquias, 10 anos, comentou sobre a satisfa\u00e7\u00e3o em treinar ao lado de um preparador f\u00edsico gabaritado.<\/p>\n\n\n\n<p>\u201cPoder treinar e ser treinado por uma pessoa reconhecida n\u00e3o tem pre\u00e7o. Estou muito feliz. Gostei muito da presen\u00e7a do \u00eddolo aqui\u201d, destacou o aluno.<\/p>\n\n\n\n<p>A estudante Rebeca Miethe, de 13 anos, integrante do projeto, disse que o encontro com o atleta a ajudou a entender melhor sobre o atletismo.<\/p>\n\n\n\n<p>\u201cAmei esse encontro, achei super interessante a aula que recebemos. Com certeza irei levar para o meu cotidiano\u201d, concluiu.<\/p>\n\n\n\n<p><strong>Sobre o projeto Maric\u00e1 + Esporte 2<\/strong><\/p>\n\n\n\n<p>O projeto oferece aulas gratuitas de dezenas de modalidades esportivas, como futebol, v\u00f4lei, lutas, gin\u00e1stica e exerc\u00edcios aer\u00f3bicos em 20 n\u00facleos do munic\u00edpio. Os polos contam com aulas voltadas para crian\u00e7as, adolescentes e adultos, com atividades esportivas entre 06h30 e 20h, mantendo-se todos os protocolos de seguran\u00e7a contra a Covid-19, como o uso obrigat\u00f3rio de m\u00e1scaras de prote\u00e7\u00e3o e disponibiliza\u00e7\u00e3o de \u00e1lcool em gel nos espa\u00e7os.<\/p>\n\n\n\n<p><strong>Quem \u00e9 Carlos Alberto Lancetta<\/strong><\/p>\n\n\n\n<p>Carlos Alberto Lancetta foi presidente da Federa\u00e7\u00e3o de Atletismo do Rio de Janeiro, em tr\u00eas mandatos. Tamb\u00e9m foi secret\u00e1rio de Esporte e Lazer da Prefeitura do Rio de Janeiro, t\u00e9cnico da sele\u00e7\u00e3o brasileira de Atletismo nos Jogos Ol\u00edmpicos de 1976 em Montreal, no Canad\u00e1, e de 1980, na R\u00fassia. Preparador f\u00edsico do Botafogo, Vasco, Fluminense, Flamengo e Am\u00e9rica, Lancetta foi tamb\u00e9m gestor de futebol do Vasco e do Botafogo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1 realizou nesta quinta-feira (18\/11) a Cl\u00ednica de Atletismo e Futebol no Parque a C\u00e9u Aberto do<\/p>\n","protected":false},"author":1,"featured_media":30683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[],"class_list":["post-30682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=30682"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30682\/revisions"}],"predecessor-version":[{"id":30684,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30682\/revisions\/30684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/30683"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=30682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=30682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=30682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}