{"id":30991,"date":"2021-11-27T09:39:35","date_gmt":"2021-11-27T12:39:35","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=30991"},"modified":"2021-11-27T09:39:36","modified_gmt":"2021-11-27T12:39:36","slug":"prova-do-sistema-de-avaliacao-da-educacao-basica-saeb-e-aplicada-nas-escolas-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/11\/27\/prova-do-sistema-de-avaliacao-da-educacao-basica-saeb-e-aplicada-nas-escolas-de-marica\/","title":{"rendered":"Prova do Sistema de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Saeb) \u00e9 aplicada nas escolas de Maric\u00e1"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, informa que a prova do Sistema de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Saeb) j\u00e1 est\u00e1 sendo aplicada em todas as escolas do munic\u00edpio e deve ser feita por alunos do 5\u00b0 e 9\u00b0 ano do ensino fundamental, al\u00e9m do 3\u00b0 ano do ensino m\u00e9dio. A avalia\u00e7\u00e3o mede o n\u00edvel de aprendizado nessas faixas et\u00e1rias, resultando no \u00cdndice de Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (IDEB), junto a outras vari\u00e1veis.<\/p>\n\n\n\n<p>A data das provas e os locais de aplica\u00e7\u00e3o ser\u00e3o divulgados progressivamente nas redes sociais da Secretaria Municipal de Educa\u00e7\u00e3o e das unidades escolares. Os pais devem ficar atentos e, em casos de d\u00favidas, entrar em contato com as unidades escolares dos filhos.&nbsp;<\/p>\n\n\n\n<p>O subsecret\u00e1rio de Educa\u00e7\u00e3o, Rodrigo Moura, refor\u00e7ou a import\u00e2ncia do Saeb para o processo educativo e os avan\u00e7os de Maric\u00e1 na estrutura\u00e7\u00e3o das unidades de ensino.<\/p>\n\n\n\n<p>\u201cA escola \u00e9 da comunidade, \u00e9 de todos. Se conseguirmos alcan\u00e7ar as metas estabelecidas pelo Minist\u00e9rio da Educa\u00e7\u00e3o, estamos atingindo tamb\u00e9m o que projetamos aos nossos alunos. Investimos na forma\u00e7\u00e3o de professores, na amplia\u00e7\u00e3o dos espa\u00e7os e na conectividade, aspectos que queremos que impactem no processo de ensino e aprendizagem. Confiamos que vamos atingir essa meta, porque nossa rede de ensino est\u00e1 muito aplicada a isso, sem medir esfor\u00e7os\u201d, destacou.<\/p>\n\n\n\n<p>\u00c9 importante ressaltar que todas as escolas de Maric\u00e1 seguem r\u00edgidos protocolos contra a Covid-19, como disponibiliza\u00e7\u00e3o de \u00e1lcool em gel, distanciamento m\u00ednimo de 1,5m e uso obrigat\u00f3rio de m\u00e1scaras.<\/p>\n\n\n\n<p><strong>O Saeb<\/strong><\/p>\n\n\n\n<p>O Sistema de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Saeb) \u00e9 um conjunto de avalia\u00e7\u00f5es que permite realizar um diagn\u00f3stico da educa\u00e7\u00e3o b\u00e1sica brasileira. Por meio de testes e question\u00e1rios, aplicados a cada dois anos na rede p\u00fablica, o Saeb reflete os n\u00edveis de aprendizagem dos estudantes avaliados, explicando esses resultados de forma contextual.<\/p>\n\n\n\n<p>O Saeb permite que as escolas e as redes municipais e estaduais de ensino avaliem a qualidade da educa\u00e7\u00e3o oferecida aos estudantes. O resultado da avalia\u00e7\u00e3o \u00e9 um indicativo da qualidade do ensino brasileiro e oferece subs\u00eddios para a elabora\u00e7\u00e3o, o monitoramento e o aprimoramento de pol\u00edticas educacionais com base em evid\u00eancias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, informa que a prova do Sistema de Avalia\u00e7\u00e3o da<\/p>\n","protected":false},"author":1,"featured_media":30992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-30991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=30991"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30991\/revisions"}],"predecessor-version":[{"id":30993,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/30991\/revisions\/30993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/30992"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=30991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=30991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=30991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}