{"id":31790,"date":"2021-12-24T07:46:52","date_gmt":"2021-12-24T10:46:52","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=31790"},"modified":"2021-12-24T07:46:53","modified_gmt":"2021-12-24T10:46:53","slug":"prefeitura-oferece-ceia-de-natal-e-leva-esperanca-a-quem-precisa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2021\/12\/24\/prefeitura-oferece-ceia-de-natal-e-leva-esperanca-a-quem-precisa\/","title":{"rendered":"Prefeitura oferece ceia de Natal e leva esperan\u00e7a a quem precisa"},"content":{"rendered":"\n<p>Amor ao pr\u00f3ximo, doa\u00e7\u00e3o e esperan\u00e7a. Foi com esses sentimentos que a Prefeitura de Maric\u00e1 promoveu um almo\u00e7o de Natal no Restaurante Municipal Mauro Alem\u00e3o, em Ino\u00e3, nesta quinta-feira (23\/12).&nbsp; Para celebrar a confraterniza\u00e7\u00e3o, a uni\u00e3o, a paz e a esperan\u00e7a de dias melhores, mais de 740 pessoas participaram da refei\u00e7\u00e3o comemorativa, com card\u00e1pio diferenciado e pre\u00e7o m\u00f3dico: apenas R$ 2.<\/p>\n\n\n\n<p>Foi uma oportunidade de as fam\u00edlias mais humildes poderem sentar \u00e0 mesa, ter uma ceia antecipada de Natal e guardar para sempre essa lembran\u00e7a. As op\u00e7\u00f5es eram fartas: chester e pernil assados, farofa, arroz e salpic\u00e3o, al\u00e9m de rabanada de sobremesa.<\/p>\n\n\n\n<p>O militar Joilson de Ara\u00fajo, de 39 anos, levou a fam\u00edlia pela primeira vez ao restaurante municipal, e gostou do que viu e do que saboreou.<\/p>\n\n\n\n<p>\u201cAdorei tudo, da ideia do card\u00e1pio ao ambiente familiar. \u00c9 uma \u00f3tima iniciativa da prefeitura, que atende muita gente que precisa\u201d, disse ele, acompanhado da mulher e do filho Jo\u00e3o Gabriel, de 4 anos.<\/p>\n\n\n\n<p><strong>\u201dA cidade se reencontra aqui, em torno da mesa\u201d, diz prefeito<\/strong><\/p>\n\n\n\n<p>De acordo com a Secretaria de Economia Solid\u00e1ria, o almo\u00e7o natalino foi uma ideia conjunta com a empresa que administra o restaurante.&nbsp; O prefeito Fabiano Horta esteve no local acompanhado da primeira-dama Rosana Horta e do vice-prefeito, Diego Zeidan.<\/p>\n\n\n\n<p>\u201cEste fim de ano \u00e9 de reencontro coletivo. J\u00e1 temos 87,7% dos moradores vacinados e o esp\u00edrito natalino carrega esse valor e agrega o afeto tamb\u00e9m. A cidade se reencontra aqui, em torno da mesa, de uma ceia de natal. Temos retorno positivo com a satisfa\u00e7\u00e3o das pessoas que est\u00e3o fazendo sua alimenta\u00e7\u00e3o com comida de qualidade\u201d, afirmou o prefeito.<\/p>\n\n\n\n<p>Para atender mais pessoas, na v\u00e9spera de Natal, sexta-feira, 24\/12, o restaurante abrir\u00e1 mais cedo, \u00e0s 10h, e funcionar\u00e1 at\u00e9 as 13h. No card\u00e1pio, frango xadrez, copa lombo ao molho, batata saut\u00e9, arroz, feij\u00e3o e salada de alface com pepino.<\/p>\n\n\n\n<p><strong>Seguran\u00e7a alimentar<\/strong><\/p>\n\n\n\n<p>Inaugurado no dia 25 de agosto de 2021, e aberto ao p\u00fablico cinco dias depois, o Restaurante Municipal Mauro Alem\u00e3o oferece refei\u00e7\u00f5es de segunda a sexta-feira, com caf\u00e9 da manh\u00e3 a R$ 1 real e almo\u00e7o a R$ 2 reais, com foco na seguran\u00e7a alimentar da popula\u00e7\u00e3o que mais precisa. Os pratos s\u00e3o preparados com alimentos org\u00e2nicos, de alta qualidade, produzidos em parte na Fazenda P\u00fablica Joaqu\u00edn Pi\u00f1ero, no Espraiado, a partir de programa desenvolvido pela Secretaria Municipal de Agricultura, Pecu\u00e1ria e Pesca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amor ao pr\u00f3ximo, doa\u00e7\u00e3o e esperan\u00e7a. Foi com esses sentimentos que a Prefeitura de Maric\u00e1 promoveu um almo\u00e7o de Natal<\/p>\n","protected":false},"author":1,"featured_media":31791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-31790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=31790"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31790\/revisions"}],"predecessor-version":[{"id":31792,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31790\/revisions\/31792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/31791"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=31790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=31790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=31790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}