{"id":31970,"date":"2022-01-02T18:40:49","date_gmt":"2022-01-02T21:40:49","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=31970"},"modified":"2022-01-02T18:40:50","modified_gmt":"2022-01-02T21:40:50","slug":"itaipuacu-proeis-prende-acusado-de-ser-mandante-do-crime-que-terminou-com-pm-morto","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/01\/02\/itaipuacu-proeis-prende-acusado-de-ser-mandante-do-crime-que-terminou-com-pm-morto\/","title":{"rendered":"Itaipua\u00e7u: PROEIS prende acusado de ser mandante do crime que terminou com PM morto"},"content":{"rendered":"\n<p>Um homem acusado de ser o mandante do crime que terminou com um PM morto a tiros em Itaipua\u00e7u, foi preso por policiais militares do Programa Estadual de Integra\u00e7\u00e3o na Seguran\u00e7a (PROEIS), na tarde deste domingo (02).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, agentes da Delegacia de Maric\u00e1 investigaram e identificaram o endere\u00e7o do acusado.<\/p>\n\n\n\n<p>O homem \u00e9 dono de imobili\u00e1ria e foi preso em casa, sem oferecer resist\u00eancia.\u00a0<\/p>\n\n\n\n<p>O policial militar Alex Correa Pereira, de 47 anos, morreu no Hospital Municipal Conde Modesto Leal, no Centro de Maric\u00e1, neste s\u00e1bado.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem acusado de ser o mandante do crime que terminou com um PM morto a tiros em Itaipua\u00e7u, foi<\/p>\n","protected":false},"author":1,"featured_media":31766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-31970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=31970"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31970\/revisions"}],"predecessor-version":[{"id":31971,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/31970\/revisions\/31971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/31766"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=31970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=31970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=31970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}