{"id":32122,"date":"2022-01-07T07:20:04","date_gmt":"2022-01-07T10:20:04","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=32122"},"modified":"2022-01-07T07:20:06","modified_gmt":"2022-01-07T10:20:06","slug":"marisa-orth-e-regina-case-se-emocionam-ao-ganhar-livro-sobre-casa-de-darcy-ribeiro-em-marica-rj","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/01\/07\/marisa-orth-e-regina-case-se-emocionam-ao-ganhar-livro-sobre-casa-de-darcy-ribeiro-em-marica-rj\/","title":{"rendered":"Marisa Orth e Regina Cas\u00e9 se emocionam ao ganhar livro sobre casa de Darcy Ribeiro em Maric\u00e1-RJ"},"content":{"rendered":"\n<p>Duas das mais importantes e consagradas atrizes da televis\u00e3o brasileira \u2013 Marisa Orth e Regina Cas\u00e9 \u2013 compartilharam no Instagram a emo\u00e7\u00e3o que sentiram ao receber um presente especial: o livro \u201cDarcy Ribeiro em Maric\u00e1, a utopia \u00e9 aqui\u201d. A obra, com curadoria do artista pl\u00e1stico e designer Gringo Cardia e produzida com apoio da Prefeitura da cidade, localizada na Regi\u00e3o Metropolitana do Rio de Janeiro, marca o in\u00edcio das celebra\u00e7\u00f5es pelo centen\u00e1rio do antrop\u00f3logo e educador, cuja trajet\u00f3ria inspira projetos sociais no munic\u00edpio.<\/p>\n\n\n\n<p>\u201c\u00c9 um livra\u00e7o!\u201d, festejou Marisa. \u201cEstou doida pra ir a Maric\u00e1\u201d, confessou Regina.<\/p>\n\n\n\n<p>O livro \u00e9 sobre a casa onde Darcy morou na Praia de Cordeirinho, em Maric\u00e1, local que ele dizia adorar. O im\u00f3vel, com projeto original de Oscar Niemeyer e inteiramente restaurado, est\u00e1 aberto \u00e0 visita\u00e7\u00e3o p\u00fablica e vai virar museu.<\/p>\n\n\n\n<p>\u201cNa casa que foi do Darcy Ribeiro em Maric\u00e1, que \u00e9 um lugar lindo, est\u00e3o fazendo esse museu. Gringo Cardia, Maric\u00e1, que m\u00e1ximo! Obrigada, Gringo! Obrigada, Darcy! Obrigada, Maric\u00e1! Sensacional!\u201d, enalteceu Marisa Orth, na noite desta quinta-feira (6\/12), em seus Stories.<\/p>\n\n\n\n<p>Folheando as p\u00e1ginas do livro, assim como fez Marisa, Regina Cas\u00e9 tamb\u00e9m foi s\u00f3 elogios ao trabalho. \u201cO livro \u00e9 lindo, uma joia feita pelo Gringo Cardia. Estou doida para ir a Maric\u00e1 s\u00f3 para ver isso de perto, deve ser uma coisa linda\u201d, afirmou a atriz e apresentadora no v\u00eddeo que postou na ter\u00e7a, dia 4.<\/p>\n\n\n\n<p><strong>Mais sobre a casa de Darcy<\/strong><\/p>\n\n\n\n<p>S\u00e3o 11 c\u00f4modos, em formato c\u00f4ncavo e com paredes em curvas, similares a uma oca, uma refer\u00eancia aos povos ind\u00edgenas, admirados por Darcy Ribeiro. Na entrada principal, h\u00e1 uma est\u00e1tua de bronze do antrop\u00f3logo posicionada de frente \u00e0 praia, em alus\u00e3o \u00e0 sua paix\u00e3o pela Praia de Cordeirinho. Dentro, est\u00e3o objetos pessoais dele e estruturas que remetem \u00e0 sua trajet\u00f3ria. O im\u00f3vel passou para a administra\u00e7\u00e3o municipal por meio de um comodato, assinado em fevereiro de 2009 junto \u00e0 Funda\u00e7\u00e3o Darcy Ribeiro, com objetivo de resgatar e compartilhar as ideias do antrop\u00f3logo.<\/p>\n\n\n\n<p><strong>Um circuito inteiramente cultural<\/strong><\/p>\n\n\n\n<p>Maric\u00e1 criou o Circuito Cultural Caminho das Artes onde, al\u00e9m da resid\u00eancia de Darcy, h\u00e1 casas de um grupo de personagens com import\u00e2ncia art\u00edstica, antropol\u00f3gica e cultural na cidade, como as de Maysa, Beth Carvalho e Jo\u00e3o Saldanha.<\/p>\n\n\n\n<p><strong>Uma cidade fora da curva<\/strong><\/p>\n\n\n\n<p>A beleza de Maric\u00e1 \u00e9 considerada esplendorosa \u00e0 pr\u00e1tica do turismo, com praias, montanhas, lagoas e cachoeiras. O munic\u00edpio oferece transporte de massa de gra\u00e7a aos moradores em \u00f4nibus, vans e bicicletas compartilhadas, e \u00e9 ainda pioneiro na transfer\u00eancia de renda por meio de uma moeda social (Mumbuca) aos habitantes que mais precisam \u2013, iniciativa que colaborou diretamente para o IBGE apontar Maric\u00e1, no fim de 2021, como a cidade com maior crescimento de participa\u00e7\u00e3o do PIB no pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas das mais importantes e consagradas atrizes da televis\u00e3o brasileira \u2013 Marisa Orth e Regina Cas\u00e9 \u2013 compartilharam no Instagram<\/p>\n","protected":false},"author":1,"featured_media":32123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-32122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/32122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=32122"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/32122\/revisions"}],"predecessor-version":[{"id":32124,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/32122\/revisions\/32124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/32123"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=32122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=32122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=32122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}