{"id":33133,"date":"2022-01-30T19:20:20","date_gmt":"2022-01-30T22:20:20","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=33133"},"modified":"2022-01-30T19:21:48","modified_gmt":"2022-01-30T22:21:48","slug":"acidente-e-registrado-na-estrada-dos-cajueiros-2","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/01\/30\/acidente-e-registrado-na-estrada-dos-cajueiros-2\/","title":{"rendered":"Acidente \u00e9 registrado na Estrada dos Cajueiros\u00a0"},"content":{"rendered":"\n<p>Um acidente entre dois carros foi registrado na Estrada dos Cajueiros, na tarde deste domingo (30).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, a colis\u00e3o aconteceu em um dos acessos a via que est\u00e1 em obra.<\/p>\n\n\n\n<p>Bombeiros do Destacamento de Maric\u00e1 foram acionados para o local e prestaram os primeiros socorros para os envolvidos do acidente.<\/p>\n\n\n\n<p>Policiais militares seguiram at\u00e9 o local e registraram a ocorr\u00eancia.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente entre dois carros foi registrado na Estrada dos Cajueiros, na tarde deste domingo (30). Segundo informa\u00e7\u00f5es, a colis\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":33135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-33133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/33133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=33133"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/33133\/revisions"}],"predecessor-version":[{"id":33138,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/33133\/revisions\/33138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/33135"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=33133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=33133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=33133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}